{"id":10256,"date":"2024-03-15T14:56:00","date_gmt":"2024-03-15T13:56:00","guid":{"rendered":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/?p=10256"},"modified":"2026-04-09T11:10:41","modified_gmt":"2026-04-09T09:10:41","slug":"online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023","status":"publish","type":"post","link":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/","title":{"rendered":"Online il nuovo calendario del colloquio di selezione per il bando SCU 2023"},"content":{"rendered":"\n<p>\u00c8 online il nuovo calendario del colloquio di selezione del bando SCU 2023 relativo al progetto&nbsp;<em>Al servizio degli anziani 2024<\/em>.<\/p>\n\n\n\n<p>Il colloquio di selezione si terr\u00e0 il<strong>&nbsp;26 marzo<\/strong>, presso la sede della Fondazione Ravasi Garzanti,&nbsp;<strong>in via Monte Rosa 19, Milano cap. 20149<\/strong><\/p>\n\n\n\n<p>Per scoprire il giorno e l\u2019orario di convocazione, i candidati sono pregati di consultare il calendario,&nbsp;disponibile qui:&nbsp;<a href=\"https:\/\/fondazioneravasi-garzanti.org\/frg_uploads\/2024\/03\/CALENDARIO-COLLOQUIO-SELEZIONE-PROGETTO-SCU_Fondazione-Ravasi-Garzanti.docx\">CALENDARIO COLLOQUIO SELEZIONE PROGETTO SCU_Fondazione Ravasi Garzanti<\/a><\/p>\n\n\n\n<p>Come previsto dal bando, la pubblicazione del calendario avviene almeno dieci giorni prima della data di convocazione e vale come notifica della convocazione.<\/p>\n\n\n\n<p>Nel rispetto della privacy, si \u00e8 scelto di non pubblicare il nominativo del candidato, ma il numero di riferimento domanda, che \u00e8 possibile trovare in alto a sinistra su ogni domanda generata dal sistema, al momento della presentazione della propria candidatura.<\/p>\n\n\n\n<p>Per eventuali supporti, scrivere a&nbsp;<a href=\"mailto:serviziocivile@assifero.org\">serviziocivile@assifero.org<\/a>&nbsp;o&nbsp;<a href=\"mailto:serviziocivile@fondazioneravasi-garzanti.org\">serviziocivile@fondazioneravasi-garzanti.org<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 online il nuovo calendario del colloquio di selezione del bando SCU 2023 relativo al progetto&nbsp;Al servizio degli anziani 2024. Il colloquio di selezione si terr\u00e0 il&nbsp;26 marzo, presso la sede della Fondazione Ravasi Garzanti,&nbsp;in&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[26],"tags":[34],"class_list":["post-10256","post","type-post","status-publish","format-standard","hentry","category-news-fondazione","tag-scu"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Online il nuovo calendario del colloquio di selezione per il bando SCU 2023 - Fondazione Ravasi Garzanti Onlus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online il nuovo calendario del colloquio di selezione per il bando SCU 2023 - Fondazione Ravasi Garzanti Onlus\" \/>\n<meta property=\"og:description\" content=\"\u00c8 online il nuovo calendario del colloquio di selezione del bando SCU 2023 relativo al progetto&nbsp;Al servizio degli anziani 2024. Il colloquio di selezione si terr\u00e0 il&nbsp;26 marzo, presso la sede della Fondazione Ravasi Garzanti,&nbsp;in...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Ravasi Garzanti Onlus\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-15T13:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T09:10:41+00:00\" \/>\n<meta name=\"author\" content=\"Francesca Panzarin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesca Panzarin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/news-fondazione\\\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/news-fondazione\\\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\\\/\"},\"author\":{\"name\":\"Francesca Panzarin\",\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/#\\\/schema\\\/person\\\/d8b962d7382064dcb97e8f443462ed00\"},\"headline\":\"Online il nuovo calendario del colloquio di selezione per il bando SCU 2023\",\"datePublished\":\"2024-03-15T13:56:00+00:00\",\"dateModified\":\"2026-04-09T09:10:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/news-fondazione\\\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\\\/\"},\"wordCount\":160,\"commentCount\":0,\"keywords\":[\"SCU\"],\"articleSection\":[\"Fondazione\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/news-fondazione\\\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/news-fondazione\\\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\\\/\",\"url\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/news-fondazione\\\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\\\/\",\"name\":\"Online il nuovo calendario del colloquio di selezione per il bando SCU 2023 - Fondazione Ravasi Garzanti Onlus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/#website\"},\"datePublished\":\"2024-03-15T13:56:00+00:00\",\"dateModified\":\"2026-04-09T09:10:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/#\\\/schema\\\/person\\\/d8b962d7382064dcb97e8f443462ed00\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/news-fondazione\\\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/news-fondazione\\\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/news-fondazione\\\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online il nuovo calendario del colloquio di selezione per il bando SCU 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/#website\",\"url\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/\",\"name\":\"Fondazione Ravasi Garzanti Onlus\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/#\\\/schema\\\/person\\\/d8b962d7382064dcb97e8f443462ed00\",\"name\":\"Francesca Panzarin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dde1cdd864b55a7053cb5b258e3f5bd743f181feb569d513bff236ce1fac20f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dde1cdd864b55a7053cb5b258e3f5bd743f181feb569d513bff236ce1fac20f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dde1cdd864b55a7053cb5b258e3f5bd743f181feb569d513bff236ce1fac20f?s=96&d=mm&r=g\",\"caption\":\"Francesca Panzarin\"},\"url\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/author\\\/francesca-panzarin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Online il nuovo calendario del colloquio di selezione per il bando SCU 2023 - Fondazione Ravasi Garzanti Onlus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/","og_locale":"it_IT","og_type":"article","og_title":"Online il nuovo calendario del colloquio di selezione per il bando SCU 2023 - Fondazione Ravasi Garzanti Onlus","og_description":"\u00c8 online il nuovo calendario del colloquio di selezione del bando SCU 2023 relativo al progetto&nbsp;Al servizio degli anziani 2024. Il colloquio di selezione si terr\u00e0 il&nbsp;26 marzo, presso la sede della Fondazione Ravasi Garzanti,&nbsp;in...","og_url":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/","og_site_name":"Fondazione Ravasi Garzanti Onlus","article_published_time":"2024-03-15T13:56:00+00:00","article_modified_time":"2026-04-09T09:10:41+00:00","author":"Francesca Panzarin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Francesca Panzarin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/#article","isPartOf":{"@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/"},"author":{"name":"Francesca Panzarin","@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/#\/schema\/person\/d8b962d7382064dcb97e8f443462ed00"},"headline":"Online il nuovo calendario del colloquio di selezione per il bando SCU 2023","datePublished":"2024-03-15T13:56:00+00:00","dateModified":"2026-04-09T09:10:41+00:00","mainEntityOfPage":{"@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/"},"wordCount":160,"commentCount":0,"keywords":["SCU"],"articleSection":["Fondazione"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/","url":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/","name":"Online il nuovo calendario del colloquio di selezione per il bando SCU 2023 - Fondazione Ravasi Garzanti Onlus","isPartOf":{"@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/#website"},"datePublished":"2024-03-15T13:56:00+00:00","dateModified":"2026-04-09T09:10:41+00:00","author":{"@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/#\/schema\/person\/d8b962d7382064dcb97e8f443462ed00"},"breadcrumb":{"@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/news-fondazione\/online-il-nuovo-calendario-del-colloquio-di-selezione-per-il-bando-scu-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/"},{"@type":"ListItem","position":2,"name":"Online il nuovo calendario del colloquio di selezione per il bando SCU 2023"}]},{"@type":"WebSite","@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/#website","url":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/","name":"Fondazione Ravasi Garzanti Onlus","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/#\/schema\/person\/d8b962d7382064dcb97e8f443462ed00","name":"Francesca Panzarin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7dde1cdd864b55a7053cb5b258e3f5bd743f181feb569d513bff236ce1fac20f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7dde1cdd864b55a7053cb5b258e3f5bd743f181feb569d513bff236ce1fac20f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7dde1cdd864b55a7053cb5b258e3f5bd743f181feb569d513bff236ce1fac20f?s=96&d=mm&r=g","caption":"Francesca Panzarin"},"url":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/author\/francesca-panzarin\/"}]}},"_links":{"self":[{"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/posts\/10256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/comments?post=10256"}],"version-history":[{"count":1,"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/posts\/10256\/revisions"}],"predecessor-version":[{"id":10257,"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/posts\/10256\/revisions\/10257"}],"wp:attachment":[{"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/media?parent=10256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/categories?post=10256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/tags?post=10256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}