{"id":11497,"date":"2026-04-21T12:13:40","date_gmt":"2026-04-21T10:13:40","guid":{"rendered":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/?page_id=11497"},"modified":"2026-05-12T10:18:16","modified_gmt":"2026-05-12T08:18:16","slug":"servizi","status":"publish","type":"page","link":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/","title":{"rendered":"Servizi"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11497\" class=\"elementor elementor-11497\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c359955 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"c359955\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-eb077f0 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"eb077f0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-416f4cb e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"416f4cb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fb6a93 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3fb6a93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" data-name=\"Livello 1\" viewBox=\"0 0 38.51 40.37\"><polygon points=\"7.46 22.51 .12 32.66 11.98 28.75 11.98 36.58 16.63 30.22 23.84 40.37 23.84 27.9 31.3 30.35 26.65 23.99 38.51 20.2 38.51 20.18 26.65 16.27 31.3 10.03 23.84 12.35 23.84 0 16.63 10.03 11.98 3.67 11.98 11.5 .12 7.71 7.46 17.74 0 20.19 7.46 22.51\"><\/polygon><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cosa facciamo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54bc3d8 elementor-widget elementor-widget-heading\" data-id=\"54bc3d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Servizi e progetti<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42c04d2 elementor-widget elementor-widget-heading\" data-id=\"42c04d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Il cuore operativo e filantropico della Fondazione<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-9c16588 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"9c16588\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c403d4d e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"c403d4d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a18206e e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"a18206e\" data-element_type=\"container\" data-e-type=\"container\" id=\"la-nostra-storia\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fad3003 elementor-widget elementor-widget-heading\" data-id=\"fad3003\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La rete sul territorio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43f1dbc elementor-widget elementor-widget-eael-divider\" data-id=\"43f1dbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-divider.default\">\n\t\t\t\t\t\t\t<div class=\"eael-divider-wrap divider-direction-horizontal\">\n\t\t\t\t\t\t\t<div class=\"eael-divider horizontal solid\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e824c9c elementor-widget elementor-widget-text-editor\" data-id=\"e824c9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Dal <strong>2020<\/strong>, con<strong> CuraMI &amp; ProteggiMI<\/strong>, la Fondazione ha dato avvio a un modello di prossimit\u00e0 basato su ascolto, orientamento e accompagnamento per persone anziane e caregiver, costruendo una prima rete territoriale in <strong>collaborazione con realt\u00e0 come Eureka! Cooperativa Sociale<\/strong> e <strong>Associazione In Cerchio<\/strong>.<\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Negli anni, questa esperienza si \u00e8 evoluta in un <\/span><b>sistema pi\u00f9 strutturato e scalabile<\/b><span style=\"font-weight: 400;\"> attraverso il <\/span><b>modello Hub &amp; Spoke<\/b><span style=\"font-weight: 400;\">, sviluppato grazie al confronto con fondazioni e attori del welfare e rafforzato anche dal <\/span><b>contributo di Fondazione Accenture<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Nel <\/span><b>2025<\/b><span style=\"font-weight: 400;\">, CuraMI &amp; ProteggiMI ha avviato una progressiva evoluzione, posizionandosi come uno dei nodi dell&#8217;Alleanza per la Grande Et\u00e0, rappresentando oggi il <\/span><b>cuore operativo del modello <\/b><span style=\"font-weight: 400;\">e garantendone la coerenza metodologica e la scalabilit\u00e0.<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">CuraMI &amp; ProteggiMI \u00e8 una <\/span><b>rete di sportelli gratuiti e accessibili nei quartieri<\/b><span style=\"font-weight: 400;\">, punti di riferimento per anziani e caregiver. Ogni percorso inizia con un <\/span><b>primo accesso gratuito<\/b><span style=\"font-weight: 400;\">, necessario per comprendere bisogni e fragilit\u00e0, e si traduce in una risposta personalizzata che integra servizi gratuiti e soluzioni a tariffe calmierate.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-81054b1 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"81054b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57fba45 elementor-widget elementor-widget-image\" data-id=\"57fba45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"708\" height=\"708\" src=\"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-content\/uploads\/2026\/04\/persone.svg\" class=\"attachment-full size-full wp-image-11701\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0750e62 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"0750e62\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-cc8746c e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"cc8746c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-e677163 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"e677163\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-5792af5 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"5792af5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ec95de4 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"ec95de4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e76a555 elementor-widget elementor-widget-heading\" data-id=\"e76a555\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I servizi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-6d5eec3 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"6d5eec3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fbaeca7 elementor-widget elementor-widget-heading\" data-id=\"fbaeca7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contatti<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-918fff3 elementor-widget elementor-widget-heading\" data-id=\"918fff3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><strong>Per informazioni, orientamento e accesso ai servizi:<\/strong><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdbd61e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bdbd61e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info@curamieproteggimi.it\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@curamieproteggimi.it<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:\/\/800681614\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Numero verde: 800 681 614<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-367370e e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"367370e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-bc72fa6 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"bc72fa6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e9b7f3 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"0e9b7f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" viewBox=\"0 0 435.8 486.6\"><path d=\"M265.8,289.7v30.1h25.3c10.1,0,18.3-8.2,18.3-18.3,0-6.5-5.3-11.9-11.9-11.9h-31.7Z\"><\/path><path d=\"M349.7,375.9c-.1,0-.3.2-.4.2h0l-63.8,17.4h49.8c13.9,0,27.1-5.9,36.3-16.3l28.1-32.6-50,31.3h0Z\"><\/path><path d=\"M379.8,311c-3.8,2.2-6.6,5.8-7.7,10.1-1.1,4.3-.5,8.8,1.8,12.6l.8,1.4,32.5-19.4c4.1-2.5,7.3-6.2,9.1-10.7l-11.7-8.4-24.8,14.3Z\"><\/path><path d=\"M408.9,318.6h0s-116.3,69.4-116.3,69.4l55.6-15.2,57-35.7h0c7.4-4.7,10.9-13.8,8.5-22.3-1.4,1.4-3,2.7-4.8,3.7Z\"><\/path><path d=\"M81.6,263.7h0v-27.6H31.3v46.6l6.1-3.1c13.9-7.2,28.8-12.6,44.1-15.9Z\"><\/path><path d=\"M415,285.7h0c-6.1-10.4-19.4-14.1-30-8.2l-59.2,33.1c0,.8.1,1.7.1,2.5h0c0,14.8-12,26.8-26.8,26.8h-115.5c-.9,0-1.7-.8-1.7-1.7s.8-1.7,1.7-1.7h115.5c12.9,0,23.4-10.5,23.4-23.4,0-1.1,0-2.2-.2-3.2-1.1-7.8-6.1-14.6-13.3-18,2.2,2.7,3.4,6.1,3.4,9.6,0,11.9-9.7,21.6-21.6,21.6h-26.9c-.9,0-1.7-.8-1.7-1.7v-31.8h-48c-.3,0-.5,0-.8-.2l-12-6.3c-50.9-26.8-111.6-27-162.7-.6l-21.2,11,.2,152.6,71-52.3c.3-.2.6-.3,1-.3h187.1l94.8-56.6-.8-1.4h0c-2.7-4.6-3.5-10-2.2-15.1,1.3-5.1,4.7-9.5,9.3-12.2l25.8-14.9c.6-.3,1.3-.3,1.8.1l11.7,8.4h0c1.3-5.4.4-11.2-2.4-16Z\"><\/path><path d=\"M218.9,286.3h23.4s14.9,0,14.9,0h0s42,0,42,0c12.5,0,23.3,8.6,26.1,20.7l50.9-28.5v-90.2c0-.9.8-1.7,1.7-1.7s1.7.8,1.7,1.7v47.7h0v40.6s3.8-2.1,3.8-2.1c6-3.3,13.1-4.1,19.6-2.2v-32.5h0v-72.3c0-13.9-11.2-25.2-25.1-25.3h-45.3s-11.7,0-11.7,0c-.9,0-1.7-.8-1.7-1.7v-11c-1.9-.1-3.7-.5-5.5-1.1-.9-.3-1.3-1.3-1-2.1.3-.9,1.3-1.3,2.1-1,5.6,1.9,11.8,1.1,16.7-2.4,4.8-3.4,7.7-9,7.8-14.9v-23.6c0-4.3-1.9-8.1-4.8-10.8h0c-7.6-28-18.6-25.7-37.4-23.5-.5,0-.9.2-1.3.2-2.5-5.7-8.7-9.8-15.9-9.8s-17.1,7-17.1,15.6,4,11.5,9.8,14c-2.6,8.3-1.5,17.3,3.5,23.1,18.1,20.8,20.4,26.7,20.5,28.3l-3.5,19.2c0,.5-.2.9-.5,1.2-.3.3-.7.5-1.2.5h-2.2s-7,0-7,0c-5.3-18.7-32-16.3-32-16.3h-9.9c-.8,0-1.5-.7-1.5-1.5v-1.5h18.5v-63.8c-6-14.1-23.7-20.9-38.8-17.9-15.1,3.1-25.9,16.3-25.9,31.7v50h24.3l-.2,1.5c0,.4-.2.8-.4,1.1-.3.3-.7.4-1.1.4h-4.7s-16,0-16,0c-8.1,0-17.6,5.3-22.4,16.3h-26.9c-.9,0-1.7-.8-1.7-1.7v-16.1c1.2.2,9.1,1.1,12.6-2.5,10.2-10.2,9.9-46.6,11.6-46.6h3.4v-8.5c0-6.4-3.3-12.3-8.7-15.7-5.4-3.4-41.1-15.6-51.6,10.3-8.8,21.7,6.1,41.5,6.1,41.5.4.3.7.8.7,1.3l-3.7,36.2c0,.5-.2.9-.5,1.2-.3.3-.7.5-1.2.5h-16.2s0,0,0,0h-39.4c-6.7,0-13,2.6-17.8,7.4-4.7,4.7-7.4,11.1-7.4,17.8v65.3h50.2v-44.4c0-.9.7-1.7,1.7-1.7s1.7.8,1.7,1.7v74.6c40.2-8.1,82-2,118.3,17.2l11.6,6.1h.7\"><\/path><path d=\"M218.9,245.4\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCura e salute\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64a5139 elementor-widget elementor-widget-text-editor\" data-id=\"64a5139\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Supporto domiciliare per affiancare persone anziane e caregiver nella quotidianit\u00e0.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8237ddf elementor-widget elementor-widget-bridge_button\" data-id=\"8237ddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  itemprop=\"url\" href=\"https:\/\/www.curamieproteggimi.it\/servizi-per-persone-anziane\/cura-e-salute\/\" target=\"_blank\" data-hover-background-color=\"#33BA55\" data-hover-color=\"#FFFFFF\" class=\"qbutton  default\" style=\"color: #FFFFFF; background-color:#22943F;\">Scopri di pi\u00f9<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-7fca2c3 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"7fca2c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f333694 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"f333694\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" viewBox=\"0 0 435.8 486.6\"><path d=\"M228.1,103.2l73.1,73.1,4.1,4.1c1,1,2.7,1,3.8,0l7.7-7.7c1.4-1.4,2.2-3.3,2.2-5.3s0-1.5-.3-2.2c-12.3-40.3-38.9-66.9-79.2-79.2-.7-.2-1.5-.3-2.2-.3-1.9,0-3.8.8-5.3,2.2l-7.7,7.7c-.5.5-.8,1.2-.8,1.9s.3,1.4.8,1.9l3.9,3.9Z\"><\/path><path d=\"M221.1,112.5l5.9-5.9,70.8,70.8-5.9,5.9-70.8-70.8Z\"><\/path><path d=\"M185.3,298.5c2.6.8,5.5,0,7.4-1.9l7.7-7.7c1-1,1-2.7,0-3.8l-3.9-3.9-73.1-73.1s0,0,0-.1l-4-4c-1-1-2.7-1-3.8,0l-7.7,7.7c-1.9,1.9-2.7,4.8-1.8,7.4,12.3,40.3,38.9,66.9,79.2,79.2h0Z\"><\/path><path d=\"M203.6,272l-70.8-70.8-5.9,5.9,70.8,70.8,5.9-5.9Z\"><\/path><path d=\"M204.7,123l76.2,76.1,4.1,4.1c.3.3.8.3,1.1,0l10-10c.2-.1.2-.3.2-.6s0-.4-.2-.6l-5.4-5.4-78.3-78.3c-.2-.1-.4-.2-.6-.2s-.4,0-.6.2l-10,10c-.3.3-.3.8,0,1.1l3.4,3.4Z\"><\/path><path d=\"M212.2,276.1c.3.3.8.3,1.1,0l10-10c.3-.3.3-.8,0-1.1l-4.1-4.1-76.2-76.1c0,0-.1-.1-.2-.2l-3.2-3.2c-.2-.1-.3-.2-.6-.2s-.4,0-.6.2l-10,10c-.3.3-.3.8,0,1.1l83.7,83.6Z\"><\/path><path d=\"M221.5,258.5s0,0,0,0c.7.6,1.9.6,2.5,0l54.5-54.5c.3-.3.5-.8.5-1.3s-.2-1-.5-1.3l-76.2-76.2c-.3-.3-.8-.5-1.3-.5s-1,.2-1.3.5l-54.5,54.5c-.7.7-.7,1.9,0,2.6l76.1,76.2Z\"><\/path><path d=\"M244,243.2l19.4-19.4,16.7,16.7-19.4,19.4-16.7-16.7Z\"><\/path><path d=\"M281.8,281.1l19.4-19.4,95.4,95.4-19.4,19.4-95.4-95.4Z\"><\/path><path d=\"M271.4,281c1.6,1.7,4.3,1.7,6,0l1-1,21.7-21.6,1-1c1.7-1.7,1.7-4.4,0-6l-10.7-10.7c-.8-.8-1.9-1.2-3-1.2s-2.2.4-3,1.2l-1,1-21.8,21.7h0s-.9.9-.9.9c-1.6,1.7-1.6,4.4,0,6l10.7,10.7Z\"><\/path><path d=\"M417.8,367.9l-10.7-10.7c-.8-.8-1.9-1.2-3-1.2s-2.2.4-3,1.2l-23.7,23.7c-1.7,1.7-1.7,4.4,0,6l10.7,10.7c1.6,1.7,4.3,1.7,6,0l23.7-23.7c1.6-1.7,1.6-4.4,0-6h0Z\"><\/path><path d=\"M249.7,357.2c0-13.6-11.1-24.7-24.7-24.7H71.6c-13.6,0-24.7,11.1-24.7,24.7v9.4h202.8v-9.4Z\"><\/path><path d=\"M254.9,369.8H41.7c-13.7,0-24.9,11.2-24.9,24.9v6.3h263v-6.3c0-13.7-11.2-24.9-24.9-24.9Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDiritti e protezione\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4e0deb elementor-widget elementor-widget-text-editor\" data-id=\"d4e0deb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Accompagnamento nelle pratiche amministrative e nei percorsi di tutela.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be8e8eb elementor-widget elementor-widget-bridge_button\" data-id=\"be8e8eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  itemprop=\"url\" href=\"https:\/\/www.curamieproteggimi.it\/servizi-per-persone-anziane\/diritti-e-protezione\/\" target=\"_blank\" data-hover-background-color=\"#33BA55\" data-hover-color=\"#FFFFFF\" class=\"qbutton  default\" style=\"color: #FFFFFF; background-color:#22943F;\">Scopri di pi\u00f9<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-71cc6e8 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"71cc6e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d3ed0b elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"4d3ed0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" viewBox=\"0 0 435.8 486.6\"><defs><style>      .st0 {        fill: #fff;      }    <\/style><\/defs><path d=\"M389,53.4c-1.1,2-3.4,3.3-5.1,4.1-2.4,1.1-4.4,3-5.6,5.4-2.3,4.6-5.7,7.8-8.1,10.1-.9.9-1.7,1.6-2.3,2.3-3.3,3.8-9.2,6.1-17.7,6.7-2.6.2-5.2,1.2-7.2,3l-15.2,13c-.8.6-1.8.9-2.7.6-.7-.2-1.4-.6-2-1.2-.7-.7-.8-1.5-.8-1.9,0-.8.4-1.6,1-2.1l11.3-9.5h0c3.3-2.8,3.8-7.7,1.2-11.1-2.3-2.9-4.1-6.1-5.4-9.5-2.2-5.5-2.8-10.6-2.7-14.7,13.3,4.2,24.8,7.5,28.8,8.1,3.3.5,6.1,0,6.4,0,.9-.2,1.9-.4,2.8-.7,1.6-.6,3.1-1.7,4-3.3,1.4-2.2,3.7-3.7,6.2-3.9,1.4,0,2.7.2,4,.8,3.1,1.5,6.2,2.5,9.4,2.9-.1.4-.2.7-.3.9Z\"><\/path><g><g><path d=\"M346,207.9c0-1.6,0-3.1,0-4.5,5.8-1.6,10.2-4.1,13.1-7.5.7-.8,1.7-1.7,2.8-2.8,3.2-3.1,7.6-7.3,10.7-13.4,1.3-2.6,3.5-4.8,6.3-6,2.5-1.1,5.8-3.1,7.4-6.1.2-.5.6-1.6.8-2.4l.3-1.1h-1.2c-4.1-.6-8.3-1.8-12.4-3.8-1.7-.8-3.4-1.2-5.2-1.2s-.6,0-.8,0c-3.8.3-7.4,2.5-9.4,5.8-1,1.6-2.5,2.8-4.1,3.4-1.1.4-2.2.7-3.3.9,0,0-1.6.3-3.9.3s-2.5,0-3.7-.3c0,0,0,0-.1,0-.2-1.5-.5-3.1-.8-4.6.6.1,1.2.2,1.6.3,1,.2,2,.2,3,.2,1.8,0,3.1-.2,3.1-.2.9-.2,1.8-.4,2.6-.7.8-.3,1.4-.8,1.9-1.6,2.8-4.6,7.6-7.5,12.8-7.9.4,0,.8,0,1.2,0,2.4,0,4.8.6,7.1,1.7,4.7,2.3,9.4,3.4,14,3.4h.1c1.2,0,2.2,1,2.2,2.2,0,2.1-1.4,6.7-2,7.8-1.8,3.3-4.9,6-9.4,8-1.8.8-3.3,2.2-4.2,4-3.4,6.8-8.3,11.5-11.6,14.6-1,1-1.9,1.8-2.5,2.5-3.7,4.3-9.2,7.4-16.4,9.2Z\"><\/path><path class=\"st0\" d=\"M368.6,155.6c2.3,0,4.5.5,6.6,1.6,4.8,2.3,9.6,3.5,14.4,3.5h.1c.7,0,1.2.5,1.2,1.2,0,2-1.3,6.4-1.9,7.3-1.7,3.1-4.7,5.6-8.9,7.6-2,.9-3.7,2.5-4.6,4.4-3.3,6.6-8.2,11.3-11.4,14.3-1.1,1-2,1.9-2.5,2.6-3.3,3.9-8.3,6.8-14.7,8.5,0-.9,0-1.7,0-2.5,5.6-1.6,9.9-4.2,12.8-7.6.7-.8,1.6-1.7,2.7-2.7,3.3-3.1,7.7-7.4,10.9-13.7,1.2-2.4,3.3-4.4,5.8-5.5,2.6-1.2,6.1-3.3,7.8-6.5h0c0,0,0-.1,0-.1.3-.6.7-2.1.8-2.5l.6-2.3-2.3-.3c-4-.4-8.1-1.6-12-3.6-1.8-.9-3.7-1.3-5.6-1.3s-.6,0-.9,0c-4.2.3-8,2.7-10.2,6.3-.9,1.4-2.1,2.5-3.6,3-1.1.4-2.1.6-3.2.8,0,0-1.6.3-3.7.3s-2,0-3-.2c-.1-.8-.3-1.7-.4-2.5,0,0,.1,0,.2,0,1,.2,2.1.2,3.2.2,1.9,0,3.2-.2,3.2-.2.9-.2,1.9-.4,2.7-.7,1-.3,1.8-1,2.4-2,2.6-4.3,7.1-7.1,12.1-7.4.4,0,.7,0,1.1,0h0M368.6,153.6c-.4,0-.8,0-1.3,0-5.6.4-10.7,3.5-13.6,8.4-.2.4-.7.9-1.4,1.1-.8.3-1.6.5-2.4.6,0,0-1.2.2-2.9.2s-1.9,0-2.9-.2c-.7-.1-1.7-.3-3-.6.4,2.2.8,4.5,1.2,6.8.3,0,.6.1.8.1,1.4.2,2.7.3,3.9.3,2.3,0,3.9-.3,4-.3,1.2-.2,2.3-.5,3.5-.9,1.9-.7,3.5-2,4.7-3.8,1.9-3.1,5.1-5.1,8.6-5.3.3,0,.5,0,.8,0,1.6,0,3.2.4,4.7,1.1,4.2,2.1,8.4,3.3,12.7,3.8-.3,1-.6,1.9-.7,2.2-1.5,2.8-4.6,4.6-6.9,5.7-2.9,1.3-5.3,3.6-6.7,6.5-3,6-7.3,10.1-10.5,13.1-1.1,1.1-2.1,2-2.8,2.9-2.9,3.4-7.4,5.9-13.3,7.4,0,2.2,0,4.4,0,6.6,8.1-1.8,14.2-5,18.2-9.8.5-.6,1.4-1.4,2.4-2.4,3.3-3.2,8.3-7.9,11.8-14.9.8-1.5,2.1-2.8,3.7-3.5,4.7-2.1,8-5,9.9-8.4.7-1.2,2.1-6,2.1-8.3,0-1.8-1.4-3.2-3.2-3.2h-.1c-4.5,0-9-1.1-13.5-3.3-2.4-1.2-4.9-1.8-7.5-1.8h0Z\"><\/path><\/g><g><path d=\"M149.1,243.9c-.3,0-.6,0-.9,0-.6,0-1.3-.2-1.9-.5-2.4-1-3.6-3-4.2-4.4l-.3-.7,41.7-32.2c1-.7,1.1-2.1.4-3.1-.4-.5-1.1-.9-1.7-.9s-1,.2-1.3.5l-42.4,32.7h-.3c-.4.1-.9.1-1.3.1-2.3,0-4.5-1-5.9-2.6-.1-.1-.2-.3-.3-.4-.9-1.2-1.3-2.6-1-4.1.3-1.6,1.2-3.1,2.5-4l49.5-33.6h.3c1.8.1,3.5.2,5,.2,2.4,0,5-.1,7.6-.3.2,0,.3,0,.4,0,5.5-.4,10.8-1.3,16-2.6,3.1-.8,6.3-1.7,9.5-2.9.1,0,.2,0,.2,0,7.6-2.7,14.7-6.3,21.3-10.7.5-.3.8-.8.9-1.4.1-.6,0-1.2-.3-1.7-.4-.6-1.1-1-1.8-1s-.9.1-1.2.4c-6.3,4.2-13.1,7.6-20.3,10.2h0s0,0,0,0c-.6.1-1.3.2-1.9.2-4.1,0-7.8-2.2-9.1-5.5-1.1-2.6-.4-5.1.3-6.9l.3-.7h.7c2,.3,4.1.4,6.1.4s5.4-.2,8.1-.6c4.4-.6,8.7-1.8,12.8-3.4,1.1-.4,1.7-1.7,1.2-2.9-.3-.8-1.1-1.4-2-1.4s-.5,0-.8.2c-3.8,1.5-7.8,2.5-11.8,3.1-2.5.4-5,.5-7.5.5s-4.9-.2-7.3-.5c-1.9-.3-3.5-1.2-4.5-2.6-.5-.8-.9-1.6-1-2.5-.3-1.5,0-3.1,1-4.4l.4-.7.8.3c1.4.5,2.9.8,4.3.9.8,0,1.5,0,2.3,0,3.4,0,6.8-.2,10.2-.5,3.3-.3,7.4-1,12.2-1.9l1.4-.2c.6-.1,1.1-.4,1.4-.9.3-.5.5-1.1.4-1.6-.2-1.1-1.1-1.8-2.2-1.8s-.3,0-.4,0l-1.4.2c-4.7.8-8.7,1.6-11.9,1.9-3.2.3-6.5.5-9.7.5s-1.5,0-2.2,0c-3.4,0-6.3-2.1-7.4-5.1-.1-.3-.2-.7-.3-1-.4-1.9.4-4.2,2.2-6.6l.4-.6.7.3c.6.2,1.2.4,1.9.5,3.9.8,7.8,1.2,11.8,1.3.3,0,.5,0,.8,0,4.9,0,9.8-.6,14.6-1.7,1.2-.3,1.9-1.5,1.6-2.6-.2-1-1.1-1.7-2.1-1.7s-.3,0-.5,0c-4.5,1-9,1.6-13.7,1.6h-.7c-3.7,0-7.4-.4-11-1.2-2.6-.5-4.6-2.2-5.3-4.5-.3-.8-.3-1.6-.2-2.4.4-3,3.8-6.2,8.5-6.2s.5,0,.5,0h.1c7.7,2.1,13.5,3.4,16.6,3.9,2.2.4,4.6.5,7,.5,4,0,6.9-.5,7.2-.5,2.1-.4,4.1-.9,6.2-1.6,2.9-1,5.4-3.1,7.1-5.8,4.4-7.2,12-11.9,20.2-12.5.6,0,1.2,0,1.8,0,3.9,0,7.6.9,11.2,2.7,8.7,4.3,17.8,6.8,27,7.3h1.2c0,0-.2,1.2-.2,1.2-.7,3.4-2.1,7.8-2.7,8.9-2.8,5.2-8,9.5-15.5,12.9-4.9,2.3-9,6.1-11.3,10.8-6.2,12.4-15.4,21.2-21.5,27-2.2,2.1-4,3.9-5.3,5.4-9.3,11-25.8,17.3-48.8,18.9-5.1.3-10,2.3-13.8,5.6l-43.4,37.1c-1.5,1.3-3.3,2-5.1,2h0Z\"><\/path><path d=\"M277.3,105.1c3.7,0,7.3.9,10.8,2.6,8.9,4.4,18.1,6.9,27.4,7.4-.7,3.4-2,7.7-2.6,8.7-2.7,4.9-7.7,9.2-15,12.5-5.1,2.4-9.3,6.4-11.8,11.3-6.2,12.3-15.3,21-21.3,26.7-2.2,2.1-4.1,3.9-5.4,5.5-9.2,10.7-25.3,17-48.1,18.5-5.3.4-10.4,2.4-14.4,5.9l-43.4,37.1c-1.3,1.1-2.9,1.7-4.5,1.7s-.5,0-.7,0c-.6,0-1.1-.2-1.6-.4-2.1-.9-3.2-2.6-3.7-3.9l41.1-31.7c1.4-1.1,1.7-3.1.6-4.5-.6-.8-1.6-1.2-2.5-1.2-.7,0-1.4.2-2,.7l-42.2,32.5c-.4,0-.8,0-1.2,0-2,0-3.9-.8-5.2-2.3,0-.1-.2-.2-.3-.3-.7-.9-1-2.1-.8-3.4.2-1.3,1-2.5,2.1-3.3l49.2-33.4c1.7,0,3.4.1,5,.1,2.6,0,5.1-.1,7.7-.3h0c.2,0,.3,0,.4,0,5.4-.4,10.8-1.3,16.1-2.6,3.3-.8,6.4-1.8,9.6-2.9.1,0,.2,0,.3-.1,7.5-2.7,14.7-6.3,21.4-10.8,1.5-1,1.9-3,.9-4.4-.6-.9-1.6-1.4-2.7-1.4s-1.2.2-1.8.5c-6.3,4.2-13,7.6-20.1,10.1-.6,0-1.2.1-1.7.1-3.6,0-7-1.9-8.2-4.9-.9-2.3-.3-4.6.3-6.1,2.1.2,4.1.3,6.2.3s5.5-.2,8.2-.6c4.4-.6,8.8-1.8,13-3.4,1.6-.6,2.5-2.5,1.8-4.1-.5-1.3-1.7-2-3-2s-.8,0-1.2.2c-3.7,1.5-7.6,2.5-11.6,3.1-2.4.3-4.9.5-7.3.5s-4.8-.2-7.2-.5c-1.6-.2-3-1-3.9-2.2-.5-.6-.7-1.3-.9-2-.2-1.3,0-2.6.8-3.7,1.5.6,3,.9,4.7.9.8,0,1.5,0,2.3,0,3.4,0,6.9-.2,10.2-.5,3.4-.3,7.5-1.1,12.3-1.9l1.4-.2c1.7-.3,2.9-2,2.6-3.7-.3-1.5-1.6-2.6-3.1-2.6s-.4,0-.6,0l-1.4.2c-4.7.8-8.7,1.6-11.8,1.8-3.2.3-6.4.4-9.6.4s-1.5,0-2.2,0c-3,0-5.5-1.8-6.4-4.4-.1-.3-.2-.6-.2-.9-.3-1.6.4-3.6,2-5.8.6.2,1.3.4,2,.6,3.9.8,8,1.2,12,1.3.3,0,.5,0,.8,0,5,0,10-.6,14.9-1.7,1.7-.4,2.8-2.1,2.4-3.8-.3-1.5-1.7-2.5-3.1-2.5s-.5,0-.7,0c-4.4,1-8.9,1.5-13.4,1.5s-.5,0-.7,0c-3.6,0-7.3-.4-10.8-1.1-2.2-.4-3.9-1.9-4.5-3.8-.2-.7-.3-1.3-.2-2,.4-2.7,3.5-5.4,7.6-5.4.1,0,.2,0,.3,0,8,2.1,13.6,3.4,16.7,3.9,2.6.4,5,.5,7.2.5,4.2,0,7.2-.5,7.4-.6,2.1-.4,4.2-.9,6.3-1.7,3.1-1.1,5.8-3.3,7.6-6.2,4.2-7,11.5-11.5,19.5-12,.6,0,1.2,0,1.8,0M277.3,103.1s0,0,0,0c-.6,0-1.3,0-1.9,0-8.6.6-16.5,5.5-21,13-1.5,2.5-3.9,4.4-6.5,5.4-2,.7-4,1.2-6,1.6-.1,0-3,.5-7,.5s-4.7-.2-6.9-.5c-2.2-.3-6.8-1.3-16.5-3.9h-.2c0,0-.2,0-.2,0-.1,0-.3,0-.4,0-5.4,0-9.1,3.6-9.5,7.1-.1.9,0,1.9.2,2.8.8,2.6,3.1,4.6,6,5.2,3.7.7,7.4,1.1,11.2,1.2.2,0,.5,0,.7,0,4.7,0,9.4-.5,13.9-1.6,0,0,.2,0,.3,0,.6,0,1,.4,1.2.9.2.6-.3,1.3-.9,1.4-4.7,1.1-9.6,1.7-14.4,1.7s-.5,0-.8,0c-3.9,0-7.8-.5-11.6-1.2-.6-.1-1.1-.3-1.7-.5l-1.4-.5-.9,1.2c-2,2.6-2.8,5.1-2.4,7.3,0,.4.2.8.3,1.2,1.2,3.4,4.5,5.7,8.3,5.8.7,0,1.5,0,2.2,0,3.3,0,6.6-.2,9.8-.5,3.2-.3,7.2-1,11.9-1.9l1.4-.2c0,0,.1,0,.2,0,.6,0,1.1.4,1.2,1,.1.7-.3,1.3-1,1.4l-1.4.2c-4.8.9-8.9,1.6-12.1,1.9-3.3.3-6.7.5-10.1.5s-1.5,0-2.3,0c-1.4,0-2.7-.3-4-.8l-1.5-.6-.9,1.3c-1,1.5-1.4,3.4-1.1,5.1.2,1.1.6,2,1.2,2.9,1.1,1.6,3,2.7,5.2,3,2.5.3,5,.5,7.5.5s5.1-.2,7.6-.5c4.1-.6,8.1-1.7,12-3.2.1,0,.3,0,.4,0,.5,0,.9.3,1.1.8.2.6,0,1.3-.7,1.6-4,1.6-8.3,2.7-12.6,3.3-2.6.4-5.3.6-8,.6s-4-.1-6-.3l-1.5-.2-.6,1.4c-.8,1.9-1.5,4.7-.3,7.6,1.5,3.7,5.5,6.1,10,6.1s1.4,0,2-.2h.2s.2,0,.2,0c7.2-2.6,14.1-6.1,20.5-10.3.2-.1.4-.2.7-.2.4,0,.8.2,1,.5.4.6.2,1.3-.3,1.7-6.5,4.3-13.6,7.9-21,10.6h0s0,0,0,0c0,0,0,0,0,0h0s0,0,0,0c-3.2,1.1-6.3,2.1-9.4,2.9-5.1,1.3-10.5,2.1-15.8,2.6h0s0,0,0,0c0,0-.1,0-.2,0h-.2c-2.6.2-5.1.3-7.5.3s-3.1,0-4.9-.1h-.7s-.6.3-.6.3l-49.2,33.4c-1.6,1.1-2.7,2.8-3,4.6-.3,1.8.2,3.5,1.2,4.9.1.1.2.3.4.4,1.7,1.9,4.1,3,6.7,3s1,0,1.5-.1h.5c0,0,.4-.4.4-.4l42.2-32.5c.3-.2.5-.3.7-.3.4,0,.7.2,1,.5.4.5.3,1.3-.2,1.7l-41.1,31.7-1.2.9.6,1.4c.7,1.7,2.1,3.9,4.8,5,.7.3,1.4.5,2.2.6.3,0,.7,0,1,0,2.1,0,4.1-.8,5.8-2.2l43.4-37.1c3.7-3.2,8.4-5.1,13.2-5.4,23.3-1.6,40-8,49.5-19.2,1.3-1.5,3.1-3.2,5.2-5.3,6.1-5.9,15.4-14.7,21.7-27.3,2.3-4.5,6.1-8.2,10.9-10.4,7.7-3.5,13-8,15.9-13.4.7-1.3,2.1-6,2.8-9.2l.5-2.3h-2.3c-9-.6-18-3-26.6-7.3-3.7-1.9-7.7-2.8-11.7-2.8h0Z\"><\/path><\/g><g><path d=\"M187.1,173.8c-1.1,0-2.2,0-3.3,0h-.3s-.3-.2-.3-.2c-.9-.6-2.4-2-2.7-4.2-.2-1.4.1-2.8.9-4l.3-.5,22.2,2.6-.3,1.1c-.4,1.2-.6,2.4-.6,3.6v.9s-.9,0-.9,0c-4.6.4-9.1.7-13.5.7-.5,0-1,0-1.5,0Z\"><\/path><path d=\"M182.3,165.9l20.4,2.4c-.3,1.1-.6,2.4-.6,3.8-4.5.4-9,.7-13.4.7-.5,0-1,0-1.5,0-1.1,0-2.2,0-3.3,0-.7-.5-2-1.7-2.3-3.5-.2-1.4.3-2.6.8-3.4M181.3,163.7l-.7,1.1c-.9,1.5-1.3,3.1-1,4.7.4,2.6,2.1,4.2,3.1,4.9l.5.4h.6c1.1,0,2.2,0,3.3,0s1,0,1.5,0c4.4,0,9-.3,13.6-.7l1.7-.2v-1.7c.1-1.1.3-2.2.6-3.3l.7-2.3-2.4-.3-20.4-2.4h-1.3Z\"><\/path><\/g><g><path d=\"M167,143.2c-.2,0-.5,0-.7,0-4.1-.6-8.2-1.7-12.2-3h-.2c0,0-.1-.2-.1-.2-1.4-1.1-3.3-2.9-4.5-5.6-1.2-2.6-1.5-5.6-.9-8.6l.2-1.1,1.1.3c3.5,1,7.1,1.9,10.7,2.4,1.9.3,3.9.5,5.8.7h1.4c0,.1-.5,1.4-.5,1.4-.9,2.1-1.2,4.6-.8,7.4.2,1.7.9,3.3,2,4.8l1.4,1.9-2.7-.4Z\"><\/path><path d=\"M149.5,125.9c3.6,1,7.2,1.9,10.8,2.4,1.9.3,3.9.5,5.9.7-1,2.3-1.3,4.9-.8,7.9.3,1.9,1,3.6,2.2,5.3-.4,0-.7,0-1.1-.1-4.1-.6-8.1-1.6-12-3-1.4-1-3.1-2.7-4.1-5.2-1.3-3-1.2-5.9-.8-8M147.9,123.4l-.4,2.2c-.6,3.2-.3,6.4.9,9.2,1,2.3,2.7,4.4,4.8,6l.3.2h.3c4,1.5,8.2,2.6,12.4,3.2.2,0,.5,0,.7,0h.4c0,0,4.6.7,4.6.7l-2.7-3.8c-1-1.4-1.6-2.9-1.9-4.4-.4-2.6-.2-4.9.7-6.9l1.1-2.5-2.8-.2c-1.9-.2-3.8-.4-5.7-.7-3.5-.6-7.1-1.4-10.6-2.4l-2.1-.6h0Z\"><\/path><\/g><g><path d=\"M304.2,226.4c-.6,0-1.1,0-1.6-.3-1.2-.4-2.3-1-3.2-1.8h0c-1.1-1.1-1.7-2.4-1.6-3.9,0-1.6.7-3,1.9-4l14.4-12.1c3.5-2.9,4-8,1.2-11.6-3-3.9-5.4-8.1-7.2-12.6-2.6-6.5-3.8-13.5-3.6-20.6v-1.3s1.3.4,1.3.4c16.6,5.3,30.9,9.4,36.7,10.5h.7c0,.1.1.8.1.8,1.6,10.3,2.5,21.3,2.7,32.8v.8s-.8.2-.8.2c-3,.7-6.3,1.2-9.9,1.5-3,.2-5.8,1.4-8.1,3.4l-19.4,16.6c-1,.9-2.3,1.3-3.6,1.3h0Z\"><\/path><path d=\"M305.6,159.5c16.5,5.3,31,9.4,36.8,10.5,1.6,10.2,2.5,21.1,2.6,32.6-2.9.7-6.2,1.2-9.8,1.5-3.2.2-6.3,1.5-8.7,3.6l-19.4,16.6c-.8.7-1.9,1.1-3,1.1s-.9,0-1.3-.2c-1.1-.3-2-.9-2.8-1.6h0c-.9-.9-1.3-2-1.3-3.1,0-1.3.6-2.5,1.6-3.3l14.4-12.1c3.9-3.3,4.5-9,1.4-13-2.9-3.8-5.3-7.9-7-12.3-3-7.6-3.7-14.7-3.5-20.2M303.6,156.8v2.7c-.3,7.3.9,14.4,3.6,21,1.8,4.6,4.3,8.9,7.3,12.8,2.4,3.2,2,7.7-1.1,10.2l-14.4,12.1c-1.4,1.2-2.3,2.9-2.3,4.8,0,1.8.6,3.4,1.9,4.6h0c1,1,2.2,1.7,3.5,2.1.6.2,1.3.3,1.9.3,1.6,0,3.1-.6,4.3-1.6l19.4-16.6c2.1-1.8,4.8-2.9,7.6-3.1,3.7-.3,7.1-.8,10.1-1.5l1.5-.4v-1.6c-.2-11.6-1.1-22.6-2.7-32.9l-.2-1.4-1.4-.3c-5.7-1.1-20-5.2-36.5-10.5l-2.5-.8h0Z\"><\/path><\/g><g><path d=\"M174,439v-.9c-.5-3.1-1-6.2-1.5-9.2-.5-2.4-1-4.8-1.6-7.1-2.5-10.1-12-17.4-22.6-17.4s-1.4,0-2.1,0l-30.9,2.8c-1,0-2,.1-3,.1-14.7,0-27.8-9.7-32-23.6-.2-.9-21.3-83-23.2-89.6-2.7-9.4-6.1-15.5-8.9-20.5-2.8-5-4.8-8.7-5-13.5-.1-3,4.2-10.3,11.2-22,8.3-13.9,18.6-31.1,18.7-39.5.5-58.6,33.5-110.7,84-133,16.9-7.4,36.2-11.4,55.8-11.4s50.7,6.6,71.2,18.7c14.5,9.6,26.5,21.4,35.8,35.1l1.1,1.7h-2.1c0-.1-.1-.1-.1-.1h-.2c-9.6,0-19.1-2.3-28.3-6.9-4.2-2.1-8.7-3.2-13.2-3.2s-1.4,0-2.2,0c-9.7.7-18.6,6.2-23.7,14.6-1.1,1.9-2.8,3.3-4.8,3.9-1.8.6-3.6,1.1-5.4,1.4,0,0-2.7.5-6.4.5s-4.3-.2-6.3-.5c-3.1-.5-8.8-1.8-16.4-3.9h0c-16.3-4.4-39.6-11.4-63.9-19.3-.2,0-.4-.1-.7-.1-.4,0-.8.1-1.2.3-6.2,3.6-6.4,12.4-6.4,13.4,0,5.4,2.5,9.4,4.6,11.9l.4.4-.2.5c-.9,3.2-1.6,8,.7,13.1,1.1,2.4,2.6,4.6,4.6,6.4l.4.4v.6c-.5,1.9-.7,5,.5,8.3,1.2,3.4,3.4,5.7,5,7l.5.4v.6c-.5,2-.9,6,1.3,10.1,2.2,3.9,5.6,5.8,8.1,6.7l.6.2v.6c.3,2.1,1,5.2,3.4,8,1.2,1.4,2.6,2.6,4.2,3.5l1.5.8-45.9,31.2c-2.4,1.6-4,4.1-4.4,6.9-.4,2.7.2,5.4,1.9,7.5.2.2.3.4.5.6,2.3,2.6,5.7,4.1,9.2,4.1h.9s.3.6.3.6c.9,2.3,2.8,5.4,6.7,7,1,.4,2,.7,3,.8.5,0,.9,0,1.4,0,2.9,0,5.7-1.1,8-3l43.4-37.1c3.1-2.7,7.1-4.3,11.3-4.6,24.3-1.6,41.7-8.5,51.8-20.4,1.1-1.3,2.9-3,5-5,6.3-6.1,15.8-15.2,22.4-28.2,1.9-3.8,5.2-6.9,9.2-8.8,8.4-3.8,14.3-8.8,17.5-14.8.9-1.7,3.1-8.8,3.6-13.1l.3-2.9,1.6,2.5c9,14.4,15.4,31.3,19.1,50.2l.3,1.5-1.5-.4c-5.9-1.4-18.9-5-37.6-11.1-.2,0-.4-.1-.7-.1-.4,0-.8.1-1.2.4-.6.4-.9.9-1,1.6-1,9.1.2,18.3,3.6,26.8,1.9,4.9,4.5,9.4,7.8,13.6,1.3,1.7,1.1,4.2-.6,5.5l-14.4,12.1c-2.2,1.8-3.4,4.5-3.5,7.3,0,2.7,1,5.3,3,7.2h.1c1.4,1.3,3,2.3,4.7,2.8,1,.3,1.9.5,3,.5,2.4,0,4.7-.9,6.5-2.4l19.4-16.6c1.6-1.3,3.6-2.2,5.6-2.3,3.3-.2,6.3-.7,9.2-1.3l1.2-.3v1.3c-.1,10.2-.8,21-2,32.1-5.3,32.9-17,65.5-34.8,97-10,17.7-14.3,37.6-12.6,57.4l3.9,43.2h-126.5Z\"><\/path><path d=\"M213,55.4c24.8,0,49.7,6.3,70.7,18.6,14.4,9.6,26.2,21.2,35.5,34.8,0,0,0,0-.1,0h-.3c-9.4,0-18.8-2.3-27.9-6.8-4.4-2.2-8.9-3.3-13.6-3.3s-1.5,0-2.2,0c-10,.7-19.2,6.4-24.5,15.1-1,1.7-2.5,2.9-4.3,3.5-1.7.6-3.5,1.1-5.3,1.4,0,0-2.6.5-6.3.5s-4-.1-6.1-.5c-3-.5-8.6-1.8-16.4-3.9,0,0,0,0,0,0-14.7-3.9-37-10.5-63.9-19.3-.3-.1-.6-.2-1-.2-.6,0-1.2.2-1.7.5-6.7,3.9-6.9,13.2-6.9,14.3,0,5.8,2.7,10.1,4.8,12.5-.9,3.1-1.7,8.3.7,13.8,1.1,2.5,2.8,4.8,4.9,6.7-.4,2.3-.6,5.4.7,8.8,1.3,3.6,3.5,6,5.4,7.4-.6,3.1-.5,7.1,1.6,10.7,2.3,4.2,6,6.2,8.6,7.2.3,2.4,1.1,5.6,3.6,8.5,1.4,1.7,3,2.9,4.5,3.7l-44.5,30.2c-2.6,1.8-4.4,4.5-4.8,7.6-.5,3,.3,5.9,2.1,8.3.2.2.4.4.5.7,2.5,2.9,6.2,4.5,10,4.5s.2,0,.2,0c1,2.5,3,5.8,7.2,7.5,1.1.4,2.2.7,3.3.9.5,0,1,0,1.5,0,3.1,0,6.2-1.2,8.6-3.3l43.4-37.1c3-2.5,6.8-4.1,10.7-4.4,24.5-1.7,42.2-8.6,52.5-20.7,1.1-1.3,2.9-3,5-5,6.3-6.1,15.9-15.2,22.6-28.5,1.8-3.6,4.9-6.6,8.8-8.3,8.6-3.9,14.6-9.1,18-15.3.9-1.7,3.2-9,3.7-13.4,9,14.4,15.3,31,18.9,49.9-6.5-1.5-20.1-5.4-37.5-11.1-.3-.1-.7-.2-1-.2-.6,0-1.2.2-1.7.5-.8.5-1.3,1.4-1.4,2.3-1,9.2.2,18.7,3.6,27.2,2,4.9,4.6,9.6,7.9,13.9,1,1.3.8,3.1-.4,4.2l-14.4,12.1c-2.4,2-3.8,4.9-3.9,8.1,0,3,1.2,5.9,3.4,7.9h.1c1.5,1.4,3.2,2.4,5.1,3.1,1.1.3,2.2.5,3.3.5,2.6,0,5.1-.9,7.1-2.6l19.4-16.6c1.4-1.2,3.2-1.9,5-2.1,3.3-.2,6.4-.7,9.3-1.3-.1,10.2-.8,20.8-1.9,32-5.3,32.7-17,65.2-34.7,96.6-10.1,17.9-14.5,38-12.7,58l3.8,42.1h-124.5c-.4-3.1-.9-6.2-1.4-9.2-.5-2.4-1-4.8-1.6-7.1-2.6-10.7-12.5-18.2-23.5-18.2s-1.4,0-2.2,0l-30.9,2.8c-1,0-2,.1-2.9.1-14.2,0-26.9-9.3-31-22.9,0,0-21.3-82.9-23.2-89.6-2.7-9.5-6.2-15.7-9-20.7-2.7-4.9-4.7-8.5-4.9-13-.3-6.9,29.7-46.7,29.9-61.5.5-58.2,33.2-110,83.4-132.1,17.2-7.5,36.2-11.3,55.4-11.3M213,53.4c-19.7,0-39.1,4-56.2,11.4-50.9,22.4-84.1,74.9-84.6,133.9,0,8.1-10.3,25.3-18.6,39-7.5,12.5-11.4,19.2-11.3,22.5.2,5,2.4,9,5.1,13.9,2.7,4.9,6.1,11,8.8,20.3,1.9,6.6,23,88.7,23.2,89.5h0s0,0,0,0c4.3,14.3,17.8,24.3,32.9,24.3s2.1,0,3.1-.1l30.9-2.8c.7,0,1.3,0,2,0,10.1,0,19.2,7,21.6,16.6.6,2.3,1.1,4.7,1.5,7,.6,3,1.1,6,1.4,9.1l.2,1.8h128.5l-.2-2.2-3.8-42.1c-1.8-19.6,2.5-39.3,12.4-56.8,17.8-31.6,29.6-64.4,34.9-97.3h0c0,0,0-.1,0-.1,1.2-11.1,1.8-22,2-32.2v-2.5s-2.4.5-2.4.5c-2.8.6-5.8,1-9,1.3-2.2.2-4.4,1.1-6.2,2.6l-19.4,16.6c-1.6,1.4-3.7,2.2-5.8,2.2s-1.8-.1-2.7-.4c-1.6-.5-3.1-1.4-4.4-2.5h-.1c-1.8-1.7-2.8-4.1-2.7-6.5,0-2.5,1.2-4.9,3.2-6.6l14.4-12.1c2.1-1.7,2.4-4.8.7-6.9-3.2-4.1-5.7-8.6-7.6-13.4-3.3-8.3-4.5-17.4-3.5-26.3,0-.4.2-.7.5-.9.2-.1.4-.2.7-.2s.3,0,.4,0c18.7,6.1,31.7,9.7,37.6,11.1l3,.7-.6-3c-3.7-19-10.2-36-19.2-50.5l-.8-1.3h0s-.7-1-.7-1l-1.6-2.6v.2c-9.4-13.7-21.5-25.5-36-35.2h0s0,0,0,0c-20.7-12.2-46.2-18.9-71.7-18.9h0ZM136.8,238.8c-3.2,0-6.3-1.4-8.5-3.8-.2-.2-.3-.4-.5-.6-1.5-1.9-2.1-4.3-1.7-6.8.4-2.5,1.9-4.8,4-6.3l44.5-30.2,2.7-1.9-2.9-1.6c-1.5-.8-2.9-1.9-4-3.2-2.2-2.6-2.9-5.5-3.1-7.4v-1.2c-.1,0-1.3-.4-1.3-.4-2.3-.8-5.5-2.6-7.5-6.3-2.1-3.7-1.7-7.5-1.4-9.4l.2-1.2-1-.8c-1.5-1.2-3.6-3.3-4.7-6.5-1.1-3.1-.9-6-.6-7.8l.2-1.1-.8-.8c-1.9-1.7-3.4-3.7-4.4-6-2.1-4.9-1.5-9.4-.6-12.4l.3-1-.7-.8c-2-2.3-4.4-6.2-4.3-11.2,0-.9.2-9.2,5.9-12.6.2-.1.4-.2.7-.2s.2,0,.3,0c24.4,7.9,47.7,14.9,64,19.3h0s0,0,0,0c7.7,2.1,13.4,3.4,16.5,3.9,2,.3,4.2.5,6.5.5,3.9,0,6.6-.5,6.6-.5,1.9-.3,3.8-.8,5.6-1.5,2.2-.8,4.1-2.3,5.3-4.4,5-8.2,13.5-13.5,22.9-14.1.7,0,1.4,0,2.1,0,4.4,0,8.7,1,12.7,3.1,9.3,4.6,19,7,28.8,7h.1s0,0,.1,0h1.3c0,0-.2,2.4-.2,2.4-.4,4.3-2.7,11.3-3.4,12.7-3.1,5.8-8.9,10.6-17,14.4-4.2,2-7.7,5.2-9.7,9.3-6.5,12.9-15.9,22-22.2,27.9-2.1,2-3.9,3.7-5.1,5.1-10,11.7-27.2,18.4-51.1,20-4.3.3-8.5,2-11.8,4.8l-43.4,37.1c-2.1,1.8-4.7,2.8-7.3,2.8s-.9,0-1.3,0c-.9-.1-1.9-.4-2.8-.7-3.5-1.4-5.3-4.3-6.1-6.4l-.5-1.3h-1.4s-.2,0-.2,0h0Z\"><\/path><\/g><g><path d=\"M162,123.2c-.3,0-.6,0-.8-.1-4.1-.7-8.3-1.7-12.4-3h-.2c0,0-.2-.3-.2-.3-1.5-1.6-4.1-5-4.1-9.6,0-2,.7-6.3,3-8.7l.4-.4.6.2c5.6,1.8,11.3,3.6,16.8,5.4l1.6.5-1.2,1.2c-1.6,1.5-2.7,3.5-3.2,5.6-.6,2.7-.2,5.5,1.2,7.9l1,1.8-2.5-.3Z\"><\/path><path d=\"M148,102.2c5.9,1.9,11.5,3.7,16.8,5.4-1.7,1.6-2.9,3.7-3.5,6.1-.7,3-.1,6,1.3,8.6-.4,0-.9-.1-1.3-.2-4.1-.7-8.3-1.7-12.2-3-1.3-1.4-3.8-4.6-3.8-8.9,0-1.6.5-5.8,2.7-8M147.4,99.9l-.9.9c-3.2,3.3-3.3,9.1-3.3,9.4,0,4.9,2.7,8.6,4.3,10.3l.3.4.5.2c4.1,1.4,8.4,2.4,12.5,3,.3,0,.6,0,.9.1h.5c0,0,4,.6,4,.6l-2-3.5c-1.2-2.2-1.6-4.8-1.1-7.2.4-1.9,1.4-3.7,2.9-5.1l2.4-2.3-3.2-1c-5.5-1.7-11.1-3.5-16.8-5.3l-1.2-.4h0Z\"><\/path><\/g><g><path d=\"M194.9,185.8c-1.1-.8-1.9-1.8-2.6-2.9-.7-1.1-1.1-2.3-1.3-3.6l-.2-1.1h1.1c3.8-.1,7.6-.4,11.4-.8h.7c0,0,.3.6.3.6.9,1.7,2.1,3.2,3.7,4.4l1.7,1.3-2.1.5c-4,.9-8.1,1.5-12,1.9h-.4s-.3-.2-.3-.2Z\"><\/path><path d=\"M203.4,178.4c.9,1.9,2.3,3.5,4,4.8-3.9.9-7.9,1.5-11.9,1.9-.8-.6-1.7-1.5-2.4-2.7-.7-1.1-1-2.3-1.2-3.3,3.8-.1,7.7-.4,11.5-.8M204.6,176.2h-1.4c-3.8.5-7.6.8-11.3.9h-2.3c0,0,.4,2.3.4,2.3.2,1.4.7,2.8,1.4,4,.7,1.2,1.7,2.3,2.9,3.2l.6.5h.8c4-.4,8.1-1.1,12.2-2l4.2-.9-3.4-2.6c-1.5-1.1-2.6-2.5-3.4-4.1l-.6-1.2h0Z\"><\/path><\/g><g><path d=\"M175.7,173.4c-2.6-.2-4.8-.4-6.8-.6-.9-.2-5.1-1.1-7.3-5.2-1-1.7-1.4-3.6-1.2-5.7v-1.2c0,0,1.2.3,1.2.3,3,.7,5.4,1.2,7.8,1.7,2,.4,4.1.8,6.5,1.2l1.2.2-.4,1.1c-.5,1.5-.7,3.2-.5,4.8,0,.7.3,1.4.5,2.1l.5,1.4h-1.5Z\"><\/path><path d=\"M161.4,162c2.6.6,5.2,1.2,7.8,1.7,2.2.4,4.4.8,6.6,1.2-.5,1.5-.8,3.2-.5,5.2.1.8.3,1.6.6,2.3-2.3-.2-4.5-.4-6.8-.6-.7-.1-4.6-1-6.6-4.6-1-1.9-1.2-3.7-1.1-5.1M159.6,159.5l-.2,2.3c-.2,2.2.3,4.3,1.3,6.3,2.5,4.4,7.1,5.5,8,5.6h0s0,0,0,0c2,.2,4.3.4,6.8.6l3.1.2-1-2.9c-.2-.6-.4-1.2-.5-1.9-.2-1.5,0-2.9.4-4.3l.8-2.2-2.3-.4c-2.4-.4-4.6-.8-6.5-1.2-2.3-.5-4.8-1-7.7-1.7l-2.2-.5h0Z\"><\/path><\/g><g><path d=\"M186.9,186.4c-1.8,0-3.6,0-5.3-.1h0s0,0,0,0c-.1,0-.2,0-.4,0-.8,0-5-.3-7.9-3.8-.9-1.1-1.5-2.3-2-3.6l-.4-1.4h1.5c3.5.5,7.1.7,10.5.8h.1s.1,0,.1,0c.8,0,1.5,0,2.2,0h1.1s0,.9,0,.9c.2,2.1.8,4.1,1.9,5.8l.8,1.5h-2.3Z\"><\/path><path d=\"M172.2,178.5c3.5.3,7,.5,10.6.6,0,0,.1,0,.2,0s0,0,0,0c.8,0,1.7,0,2.5,0,.2,1.8.7,4,2,6.2-.2,0-.4,0-.6,0-1.8,0-3.5,0-5.3-.1-.2,0-.3,0-.5,0-.7,0-4.5-.3-7.1-3.4-.9-1.1-1.4-2.2-1.8-3.3M169.4,176.2l.9,2.8c.4,1.5,1.2,2.8,2.1,4,3.2,3.8,7.7,4.1,8.6,4.1,0,0,.1,0,.2,0h.1s.1,0,.1,0c1.7,0,3.6.1,5.4.1h.6s3.4,0,3.4,0l-1.7-3c-1-1.7-1.5-3.5-1.7-5.4l-.2-1.8h-1.8s-.1,0-.1,0c-.8,0-1.6,0-2.3,0h0s0,0,0,0h0s0,0,0,0h0s0,0,0,0c-3.4,0-6.9-.3-10.4-.6l-2.9-.3h0Z\"><\/path><\/g><g><path d=\"M170.2,158.4c-3.3-.7-6.8-1.4-10.2-2.2h-.2s-.1-.1-.1-.1c-1.3-.8-3.5-2.6-4.7-5.8-.5-1.3-.7-2.6-.6-4v-1.3s1.3.4,1.3.4c3.3,1,6.6,1.7,9.9,2.2,1.8.3,3.7.5,5.7.6h1.4c0,.1-.5,1.4-.5,1.4-.8,2-1.1,4.1-.7,6.1,0,.5.2,1,.4,1.5l.5,1.6-2-.4Z\"><\/path><path d=\"M155.4,146.2c3.3,1,6.7,1.8,10.1,2.3,1.9.3,3.8.5,5.7.6-.9,2.1-1.2,4.4-.8,6.7,0,.6.2,1.1.4,1.6-.1,0-.2,0-.4,0-3.4-.7-6.8-1.4-10.2-2.2-1.1-.7-3.2-2.4-4.3-5.3-.5-1.3-.6-2.6-.6-3.7M153.5,143.5v2.6c-.1,1.5.1,3,.6,4.4,1.2,3.4,3.7,5.4,5.1,6.3l.3.2h.3c3.5.9,6.9,1.7,10.3,2.3h.2s.1,0,.1,0l3.3.6-1-3.2c-.1-.5-.3-.9-.3-1.4-.3-1.9,0-3.8.7-5.6l1.1-2.6-2.8-.2c-1.9-.1-3.8-.4-5.6-.6-3.3-.5-6.6-1.2-9.8-2.2l-2.5-.8h0Z\"><\/path><\/g><g><path d=\"M196.9,130.9c-3.2-.5-6.3-1.2-9.1-1.9-5.7-1.5-11.2-3.6-16.5-6.1,0,0-.1,0-.2,0-3.3-1.2-5.2-4.7-4.5-8,.7-3.1,3.6-5.4,6.9-5.4s.4,0,.7,0h.1s0,0,0,0c9.7,3,18.7,5.6,26.6,7.9l1.8.5-1.4,1.2c-2.1,1.8-3.3,4.1-3.7,6.7-.2,1.3,0,2.6.3,3.9l.4,1.5-1.5-.2Z\"><\/path><path d=\"M173.5,110.4c.2,0,.4,0,.6,0,10.2,3.1,19.1,5.8,26.7,7.9-2.2,1.9-3.6,4.4-4,7.3-.2,1.4,0,2.9.3,4.3-3.1-.5-6.1-1.1-9.1-1.9-5.6-1.5-11.1-3.5-16.4-6,0,0-.2,0-.3-.1-2.8-1.1-4.5-4-3.8-6.8.6-2.7,3.1-4.6,6-4.6M173.5,108.4c-3.8,0-7.1,2.6-7.9,6.2-.9,3.8,1.3,7.7,5.1,9.1,0,0,0,0,0,0,5.3,2.6,11,4.6,16.7,6.1,2.9.8,6,1.4,9.2,2l3.1.5-.8-3c-.3-1.2-.4-2.4-.2-3.5.3-2.3,1.5-4.4,3.4-6.1l2.8-2.4-3.5-1c-8-2.3-16.9-4.9-26.6-7.9h-.2c0,0-.2,0-.2,0-.3,0-.5,0-.8,0h0Z\"><\/path><\/g><g><path d=\"M196.8,148.3c-7-.5-13.2-1.9-17.9-4h0s-.1,0-.1,0h-.2c-4.7-2.3-7.4-5.1-7.9-7.9-.5-3.2.2-5.7,2.2-7.2l.5-.4.5.2c4.2,1.7,8.4,3.2,12.8,4.3,3.7,1,7.5,1.8,11.3,2.3l1.4.2-.7,1.3c-1.5,2.6-2,5.2-1.5,7.7.1.6.3,1.1.4,1.6,0,.1,0,.2.1.4l.6,1.6h-1.6Z\"><\/path><path d=\"M173.5,129.8c4.2,1.7,8.5,3.2,12.9,4.4,3.8,1,7.6,1.8,11.5,2.3-1.6,2.8-2.1,5.7-1.6,8.4.1.6.3,1.2.5,1.8,0,.2.1.4.2.6-7.3-.5-13.3-2-17.6-3.9,0,0-.2,0-.2-.1,0,0-.1,0-.2,0-4.3-2-6.9-4.6-7.2-7-.4-2.9.2-5,1.8-6.3M173.1,127.5l-.9.7c-1.5,1.2-3.2,3.6-2.5,8.1.5,3.2,3.4,6.2,8.3,8.6h0s0,0,0,0c0,0,0,0,0,0h0c0,0,0,0,0,0h0c4.9,2.2,11.2,3.7,18.3,4.1l3.2.2-1.2-2.9v-.2c-.1-.1-.1-.2-.2-.3-.2-.5-.3-1-.4-1.5-.4-2.2,0-4.6,1.4-7.1l1.4-2.5-2.9-.4c-3.8-.5-7.6-1.3-11.2-2.3-4.3-1.1-8.5-2.6-12.6-4.3l-1.1-.5h0Z\"><\/path><\/g><g><path d=\"M181.7,160.3c-2.3-.3-4.4-1.6-5.4-3.5-.3-.6-.5-1.3-.6-1.9-.3-2.1.3-4.2,1.8-5.8l.5-.5.6.3c5.2,2.1,11.8,3.4,19.1,3.8h1.3c0,0-.4,1.3-.4,1.3-.6,1.6-.7,3.4-.4,5.1,0,.5.2,1.1.5,1.7l.5,1.5-17.5-2Z\"><\/path><path d=\"M178.3,149.9c5.3,2.1,11.9,3.5,19.4,3.9-.6,1.8-.8,3.7-.5,5.6.1.7.3,1.3.5,1.9l-15.9-1.8c-2-.2-3.8-1.4-4.6-2.9-.3-.5-.5-1.1-.5-1.6-.3-1.8.3-3.6,1.6-4.9M177.7,147.5l-.9,1c-1.7,1.8-2.5,4.2-2.1,6.6.1.8.4,1.5.7,2.2,1.1,2.2,3.5,3.7,6.1,4l15.9,1.8,3.2.4-1.1-3c-.2-.6-.3-1.1-.4-1.6-.3-1.5-.1-3.1.4-4.6l.8-2.5h-2.6c-7.1-.5-13.6-1.8-18.8-3.9l-1.3-.5h0Z\"><\/path><\/g><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMente e corpo\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c28e4a9 elementor-widget elementor-widget-text-editor\" data-id=\"c28e4a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Attivit\u00e0 e interventi per il benessere psicologico, relazionale e cognitivo.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c1ed20 elementor-widget elementor-widget-bridge_button\" data-id=\"7c1ed20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  itemprop=\"url\" href=\"https:\/\/www.curamieproteggimi.it\/servizi-per-persone-anziane\/mente-e-corpo\/\" target=\"_blank\" data-hover-background-color=\"#33BA55\" data-hover-color=\"#FFFFFF\" class=\"qbutton  default\" style=\"color: #FFFFFF; background-color:#22943F;\">Scopri di pi\u00f9<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c6580ee e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"c6580ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-431defc e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"431defc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06e823d elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"06e823d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 110 135\"><defs><style>      .st0 {        fill: #fff;      }    <\/style><\/defs><g id=\"Livello_2\"><path d=\"M107,54.1L55.5,11.8c-.3-.3-.7-.3-1.1,0L3,54.1c-.3.2-.4.6-.3.9s.4.6.8.6h7.6c.2,0,.4,0,.5-.2l2.1-1.7v55.1c0,.5.4.8.8.8h80.8c.5,0,.8-.4.8-.8v-55.1l2.1,1.7c.1.1.3.2.5.2h7.6c.4,0,.7-.2.8-.6s0-.7-.3-.9Z\"><\/path><\/g><g id=\"Livello_1\"><path class=\"st0\" d=\"M39.6,40.1l1.9-1.6h0c.1,0,.3,0,.4,0l.7.6h0c.1.1.3.2.4.3.1,0,.3,0,.4,0h0,0c.7,0,1.3-.6,1.3-1.3s-.6-1.7-1.5-1.9h-.3c0,0,0,0,0,0-.2,0-.3,0-.5,0h-1.6c-1.3,0-2.3,1-2.3,2.3v1.9c.2-.2.5-.3.8-.3s0,0,.1,0h0Z\"><\/path><path class=\"st0\" d=\"M45.9,57.5l.5,2.1c0,.3.2.6.3.9l5.9,1.2.8-1h0c.4-.5,1.1-.7,1.7-.3.6.3.8,1.1.5,1.6v.3c-.1,0,.8.2.8.2,0,0,0,0,0,0l7.6-2.3-.3-1.6h-1.2c0,0-.2,0-.2,0,0,0,0-.1,0-.2,0,0,0-.6,0-.6h0c0-.4-.3-.7-.7-.8-.4,0-.7.2-.8.6l-.2.9c0,.1-.1.2-.3.2h-8.4c-.1,0-.2,0-.3-.2l-.7-2.7-4.7,1.4v.4Z\"><\/path><path class=\"st0\" d=\"M39.5,42.4c0,0,.1,0,.2,0,0,0,0,.1,0,.2v3.8c0,.5.4.8.8.8s.8-.4.8-.8v-2.1c0-.2.1-.3.3-.3.8,0,1.4-.6,1.4-1.4v-2.5c-.1,0-.2,0-.3-.1-.2,0-.4-.2-.6-.4l-.5-.5-1.8,1.5c0,0-.1,0-.2,0,0,0-.1,0-.2,0-.5,0-.8.4-.8.8s.4.8.8.8Z\"><\/path><path class=\"st0\" d=\"M65.7,40.1c.2,0,.3,0,.5,0,.2,0,.3-.2.4-.3l.7-.6h0c.1,0,.3-.1.4,0l1.9,1.6s0,0,.1,0h0c.5,0,.9.2,1.1.6l.5-1.3c.3-.7.2-1.5-.2-2.2-.4-.6-1.1-1-1.9-1h-2.6c-.2,0-.3,0-.5,0h-.3c0,0,0,0,0,0-.9.2-1.5,1-1.5,1.9s.6,1.3,1.3,1.3h0Z\"><\/path><path class=\"st0\" d=\"M38.5,64.6c-1.5-.3-2.8-1.4-3.3-2.9l-2.8-8.3c0-.1,0-.3.2-.4.1,0,.3,0,.4.2l1.2,3.4,4.6-1.4-2.2-6.2c0,0,0-.1,0-.2s0-.1.2-.1c0,0,.1,0,.2,0,0,0,.1,0,.1.2l3.7,10.4,4.1.8,1.6-6.8c0-.2.2-.2.3-.2.2,0,.2.2.2.3l-.7,3.1,4.4-1.3-1.5-5.3c-.6-2.1-2.4-3.5-4.6-3.5h-2.5c0,.9-.6,1.5-1.4,1.5s-1.4-.6-1.4-1.4h0c0-.1-3.1-.1-3.1-.1-2.7,0-5,2-5.3,4.7l-1.6,13.8h10s-.7-.1-.7-.1Z\"><\/path><path class=\"st0\" d=\"M72,39.3c.7.4,1.6.3,2.2-.2.6-.5.8-1.4.5-2.2-.3-.8-1-1.3-1.9-1.3-.8,0-1.6.6-1.8,1.3.6.6,1,1.4.9,2.3h0Z\"><\/path><path class=\"st0\" d=\"M69.5,42.9s0,0,.1,0c.5,0,.8-.4.8-.8s-.4-.8-.8-.8-.1,0-.2,0c0,0-.2,0-.2,0l-1.8-1.5-.5.5h0c-.2.2-.4.3-.6.4-.1,0-.2,0-.3.1v2.3c0,.6.3,1.1.7,1.4.5.3,1,.4,1.5.2.1,0,.3,0,.4.2,0,.1,0,.3-.2.4-.1,0-.3,0-.4.1l.6,2c0,.2.2.4.4.5.2.1.4.1.6,0s.4-.2.5-.4c.1-.2.1-.4,0-.6l-1-3.4c0,0,0-.2,0-.3,0,0,.2-.1.2,0h0Z\"><\/path><path class=\"st0\" d=\"M64.4,60l4.7-1.4,1.1-8.1h0c.2-1.5,1.6-2.6,3.1-2.5,1.5.1,2.7,1.4,2.7,2.9,0,.2,0,.3,0,.5l-1.5,8.9c-.3,1.7-1.5,3-3.1,3.5l-3.6,1h12.6s-2.3-13.2-2.3-13.2h0c-.5-3-3.1-5.2-6.2-5.2h-1.1v.2c0,0,0,0,0,0,.1.4,0,.9-.2,1.2-.3.4-.7.6-1.1.6-.6,0-1.2-.4-1.3-1l-.2-.6c-3.2,1.2-5,4.5-4.5,7.9l1,5.4Z\"><\/path><path class=\"st0\" d=\"M62.7,57.6s0,0,0,.1v.2s.8,0,.8,0l-.6-3.3c-.1-.6-.1-1.1-.1-1.7l-1.9,3.4c.4-.1.8,0,1.2.2.3.2.6.6.6,1.1h0Z\"><\/path><path class=\"st0\" d=\"M47.1,66.9c0,.1.2.2.3.2l1.4-.4-1.9-.4.2.6Z\"><\/path><path class=\"st0\" d=\"M83.6,88.2l-1-2.8h0c-1.4-3.9-2.2-7.9-2.2-12.1v-8.1h-14.6s-.6.1-.6.1l-1.5,9.5h0c-.5,3.1-.5,6.2-.1,9.3l.5,4h19.5Z\"><\/path><path class=\"st0\" d=\"M66.2,97.7l-2.5,1.7h9.9l-.3-1.7h-7.1Z\"><\/path><path class=\"st0\" d=\"M65,88.7l1.4,8.4h6.8l-1.7-8.4h-6.5Z\"><\/path><path class=\"st0\" d=\"M86.4,97.7h-7.2l-2.1,1.7h9.9l-.6-1.7Z\"><\/path><path class=\"st0\" d=\"M43.7,65.6l-1.8-.4h-12.7v5.3l.5,8.9h0s0,0,0,.1l-6.8,19.7h9.6l-2.2-1.7c0,0-.1-.2,0-.3l5.8-16.8c.2-.7.3-1.5.3-2.2l-.6-6.6c0,0,0-.2,0-.2,0,0,.1,0,.2,0h2.4c.1,0,.3.1.3.2l1.1,7.8s0,0,0,0l-4.1,19.8h9.2l-2.1-1.7c0,0-.1-.2,0-.3l3.2-16.9c.1-.6.1-1.2,0-1.8l-2-13Z\"><\/path><path class=\"st0\" d=\"M86.2,97.1l-3-8.4h-7.1l3.1,8.4h6.9Z\"><\/path><path class=\"st0\" d=\"M56.2,63l-1.3-.3h0c0,0-.2,0-.2-.2,0,0,0-.2,0-.2l.3-.6c.2-.3,0-.7-.3-.9-.3-.2-.7-.1-.9.2l-.9,1.2h0c0,0-.2.1-.3.1l-12.2-2.5c0,0-.2,0-.2-.2l-1.4-3.9-4.6,1.4,1.5,4.4c.5,1.3,1.6,2.3,2.9,2.6l16.7,3.4c.2,0,.4-.1.5-.3l.7-3.6h0c0-.2,0-.4-.3-.5h0Z\"><\/path><path class=\"st0\" d=\"M57.4,67.6c.8.3,1.2,1,1.2,1.8v.6c0,.5.4.8.8.8s.8-.4.8-.8v-.6c0-.9-.3-1.7-.9-2.4l-2,.6Z\"><\/path><path class=\"st0\" d=\"M53.5,67.6c-.3.6-.5,1.2-.5,1.8v29.1c0,.5.4.8.8.8s.8-.4.8-.8v-29.1c0-.5.2-1,.6-1.4,0,0,0,0,0,0,0,0-.1,0-.2,0l-1.7-.3Z\"><\/path><path class=\"st0\" d=\"M74,60.1l1.5-8.9c0-.1,0-.3,0-.4,0-1.2-1-2.3-2.2-2.4-1.2,0-2.3.8-2.5,2.1l-1.1,8.3c0,.1,0,.2-.2.2l-12.5,3.7c.1.2.2.5.2.7l-.7,3.5c.2.1.5.1.7,0l14.2-4c1.4-.4,2.5-1.6,2.7-3h0Z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCasa e comunit\u00e0\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df3a13a elementor-widget elementor-widget-text-editor\" data-id=\"df3a13a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Soluzioni abitative pi\u00f9 sicure e accoglienti, connesse con il territorio.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b383d35 elementor-widget elementor-widget-bridge_button\" data-id=\"b383d35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  itemprop=\"url\" href=\"https:\/\/www.curamieproteggimi.it\/servizi-per-persone-anziane\/casa-e-comunita\/\" target=\"_blank\" data-hover-background-color=\"#33BA55\" data-hover-color=\"#FFFFFF\" class=\"qbutton  default\" style=\"color: #FFFFFF; background-color:#22943F;\">Scopri di pi\u00f9<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-55f1da1 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"55f1da1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83c1f0c elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"83c1f0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" viewBox=\"0 0 435.8 486.6\"><g><path d=\"M167.9,452c-22.4,0-41.7-14.9-47.5-36.5-16.6-2.8-31.8-11.3-42.9-24-11.5-13.2-17.9-30.2-17.9-47.8s.4-8.1,1.3-13.1l.2-.8.7-.5c5.2-3.5,11.3-5.3,17.5-5.3,16.7,0,30.4,13.1,31.5,29.5h7.8c-1-20.8-18.3-37.3-39.3-37.3s-14.9,2.2-21.4,6.4l-1.4.9-1.1-1.2c-12.5-13.5-19.4-31.1-19.4-49.4s9.2-41.4,25.4-55.3c0,0,0,0,0,0,0-.3,0-.5-.1-.8l-.8-3.8,3.5,1.5c5.1,2.2,10.2,3.3,15.3,3.3,21,0,38.2-16.6,39.3-37.3h-7.8c-1,16.5-14.8,29.5-31.5,29.5s-13.4-2.3-18.9-6.6l-.8-.6v-1c0-17.5,6.5-34.4,18-47.6,11.1-12.7,26.3-21.2,42.9-23.9,5.8-21.6,25.1-36.5,47.5-36.5s16.8,2.4,24.6,7l1,.6v178l-.4.5c-6.1,8.1-15.3,12.8-25.2,12.8-16.7,0-30.4-13.1-31.5-29.5h-7.8c1,20.8,18.3,37.3,39.3,37.3s15.8-2.5,22.5-7.1l3.1-2.2v153.4l-1,.6c-7.9,4.7-16.2,7-24.6,7Z\"><\/path><path d=\"M167.9,95.6c8.7,0,16.7,2.6,23.6,6.8v176.2c-5.4,7.2-13.9,12-23.6,12-16.3,0-29.5-13.3-29.5-29.5h-11.8c0,22.8,18.5,41.3,41.3,41.3s16.9-2.8,23.6-7.5v148.4c-7,4.1-14.9,6.8-23.6,6.8-22.3,0-40.9-15.5-45.8-36.3-34.2-5-60.5-34.4-60.5-70s.5-8.6,1.3-12.7c4.7-3.2,10.3-5,16.4-5,16.3,0,29.5,13.3,29.5,29.5h11.8c0-22.8-18.5-41.3-41.3-41.3s-16,2.5-22.4,6.7c-11.7-12.6-18.9-29.5-18.9-48.1s10-41.5,25.6-54.5c-.2-.7-.2-1.4-.4-2.1,5.1,2.2,10.5,3.4,16.1,3.4,22.8,0,41.3-18.5,41.3-41.3h-11.8c0,16.3-13.3,29.5-29.5,29.5s-12.6-2.2-17.7-6.2c.1-35.5,26.3-64.7,60.4-69.8,5-20.8,23.5-36.3,45.8-36.3M167.9,91.6c-22.9,0-42.7,15-49,36.8-16.5,3-31.6,11.6-42.8,24.4-11.8,13.5-18.4,30.9-18.5,48.9v2s1.6,1.2,1.6,1.2c5.9,4.6,12.9,7,20.1,7,17.1,0,31.3-12.9,33.3-29.5h3.8c-2,18.7-17.9,33.3-37.1,33.3s-9.7-1.1-14.5-3.1l-7.1-3,1.5,7.3c-16.1,14.2-25.2,34.5-25.2,56.1s7.1,36.9,20,50.8l2.3,2.5,2.8-1.8c6.1-4,13.1-6.1,20.3-6.1,19.2,0,35.1,14.6,37.1,33.3h-3.8c-2-16.6-16.2-29.5-33.3-29.5s-13.1,2-18.6,5.7l-1.4.9-.3,1.7c-.9,5.1-1.4,9.3-1.4,13.5,0,18.1,6.5,35.5,18.4,49.1,11.2,12.8,26.3,21.4,42.9,24.4,6.4,21.8,26.2,36.8,49,36.8s17.5-2.5,25.7-7.3l2-1.2v-158.4l-6.3,4.4c-6.3,4.4-13.7,6.8-21.3,6.8-19.2,0-35.1-14.6-37.1-33.3h3.8c2,16.6,16.2,29.5,33.3,29.5s20.4-5,26.8-13.6l.8-1.1V100.1l-2-1.2c-8.2-4.9-16.8-7.3-25.7-7.3h0Z\"><\/path><\/g><circle cx=\"262.4\" cy=\"131.1\" r=\"11.8\"><\/circle><circle cx=\"274.2\" cy=\"83.8\" r=\"11.8\"><\/circle><circle cx=\"297.9\" cy=\"166.5\" r=\"11.8\"><\/circle><circle cx=\"345.1\" cy=\"166.5\" r=\"11.8\"><\/circle><circle cx=\"321.5\" cy=\"60.2\" r=\"11.8\"><\/circle><circle cx=\"309.7\" cy=\"119.3\" r=\"11.8\"><\/circle><circle cx=\"404.2\" cy=\"48.4\" r=\"11.8\"><\/circle><circle cx=\"368.8\" cy=\"83.8\" r=\"11.8\"><\/circle><circle cx=\"380.6\" cy=\"142.9\" r=\"11.8\"><\/circle><circle cx=\"404.2\" cy=\"107.5\" r=\"11.8\"><\/circle><g><path d=\"M227,452c-8.5,0-16.8-2.4-24.6-7.1l-1-.6v-237l.4-.5c6.1-8.1,15.3-12.8,25.2-12.8,16.7,0,30.4,13.1,31.5,29.5h7.8c-1-20.8-18.3-37.3-39.3-37.3s-15.8,2.5-22.5,7.1l-3.1,2.2v-94.3l1-.6c6.7-4,13.9-6.3,21.5-6.8l2.6-.2-.5,2.5c-2.5,13.1-1.5,24.5,2.8,34,3.5,7.6,7.8,11.2,16.3,18.4,4.8,4,10.8,9.1,18.7,16.4,13,12.2,19.4,19.9,23.6,25,4.4,5.3,6.5,7.8,11.4,10.1,4.8,2.3,10.2,3.5,16.2,3.5s11.3-.9,17.7-2.8l2.6-.8v2.7c-.1,4.9-.7,9.9-1.7,14.8,16.1,13.9,25.4,34,25.4,55.3s-9.2,41.4-25.4,55.3c.3,1.3.5,2.6.7,3.9l.2,1.1v.4c-3.6,14.1-16.1,24-30.6,24s-30.4-13.1-31.5-29.5h-7.8c1,20.8,18.3,37.3,39.3,37.3s19.6-3.9,27-10.9l4.4-4.2-1,6c-5.3,30.6-29.2,54.2-59.7,59.3-5.8,21.6-25.1,36.5-47.5,36.5Z\"><\/path><path d=\"M224,95.9c-3.1,16.3-.5,27.6,3,35.2,5.7,12.3,13.3,14.6,35.4,35.4,26.2,24.7,25.1,30.4,35.4,35.4,4.5,2.2,10.1,3.7,17.1,3.7s11.3-.8,18.3-2.9c0,5.4-.7,10.5-1.9,15.5,15.6,13,25.6,32.6,25.6,54.5s-10,41.5-25.6,54.5c.4,1.9.7,3.8,1,5.7-3.2,12.9-14.7,22.5-28.6,22.5s-29.5-13.3-29.5-29.5h-11.8c0,22.8,18.5,41.3,41.3,41.3s21-4.4,28.4-11.5c-5.2,29.9-29.2,53.4-59.4,57.9-5,20.8-23.5,36.3-45.8,36.3s-16.7-2.6-23.6-6.8v-235.2c5.4-7.2,13.9-12,23.6-12,16.3,0,29.5,13.3,29.5,29.5h11.8c0-22.8-18.5-41.3-41.3-41.3s-16.9,2.8-23.6,7.5v-89.3c6.1-3.7,13.1-6,20.6-6.5M228.9,91.5l-5.2.4c-7.9.6-15.4,2.9-22.4,7.1l-2,1.2v99.3l6.3-4.4c6.3-4.4,13.7-6.8,21.3-6.8,19.2,0,35.1,14.6,37.1,33.3h-3.8c-2-16.6-16.2-29.5-33.3-29.5s-20.4,5-26.8,13.6l-.8,1.1v238.8l2,1.2c8.2,4.9,16.8,7.3,25.7,7.3,22.9,0,42.7-15,49-36.8,14.6-2.7,27.9-9.6,38.6-20,11.3-11.1,18.8-25.1,21.4-40.7l2.1-11.9-8.8,8.3c-7,6.7-16.2,10.4-25.7,10.4-19.2,0-35.1-14.6-37.1-33.3h3.8c2,16.6,16.2,29.5,33.3,29.5s28.8-10.5,32.5-25.5l.2-.8v-.8c-.1,0-.2-.7-.2-.7-.1-.9-.3-1.9-.5-2.8,16-14.2,25.2-34.5,25.2-56s-9.1-41.8-25.2-56c.9-4.6,1.4-9.3,1.5-14v-5.4c0,0-5.1,1.5-5.1,1.5-6.2,1.8-12,2.7-17.2,2.7s-10.9-1.1-15.4-3.3c-4.5-2.2-6.3-4.4-10.7-9.6-4.3-5.1-10.7-12.9-23.8-25.1-7.9-7.4-13.9-12.5-18.7-16.5-8.6-7.2-12.5-10.5-15.8-17.7-4.2-9.1-5.1-20.1-2.7-32.8l1-5.1h0Z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAlzheimer e decadimento\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b82284d elementor-widget elementor-widget-text-editor\" data-id=\"b82284d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Percorsi e servizi dedicati alle persone con demenza e alle loro famiglie.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d3f494 elementor-widget elementor-widget-bridge_button\" data-id=\"9d3f494\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  itemprop=\"url\" href=\"https:\/\/www.curamieproteggimi.it\/partnership\/progetto-alzheimer\/\" target=\"_blank\" data-hover-background-color=\"#33BA55\" data-hover-color=\"#FFFFFF\" class=\"qbutton  default\" style=\"color: #FFFFFF; background-color:#22943F;\">Scopri di pi\u00f9<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-5fa582b e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"5fa582b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-256f195 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"256f195\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Livello_1\" viewBox=\"0 0 435.8 486.6\"><g><path d=\"M248,73.6c-1.4.3-2.8.3-4.2,0-9.2,19.1-15.3,39.6-18.2,60.6,2.4,0,4.8.1,7.1.4,2.8-20,8.6-39.4,17.3-57.6-.9-1-1.6-2.2-2.1-3.5Z\"><\/path><path d=\"M181.9,65.1l.5.7c14.6,21.1,24.2,45.2,28,70.6,2.3-.6,4.6-1.1,7-1.4-4-26.3-14-51.4-29.2-73.3l-.5-.7c-1.1-1.6-3.3-2.1-4.9-1-1.6,1.1-2.1,3.3-1,4.9,0,0,0,.1.1.2Z\"><\/path><path d=\"M201.9,262.7v-42.9c-8.8-1-15.2-8.9-14.2-17.7,1-8.8,8.9-15.2,17.7-14.2,3.9.4,7.5,2.3,10.2,5.2,9.3-6.5,14.9-17.1,14.8-28.5,0-1,.8-1.8,1.8-1.8h10.7c10.8,0,19.6,8.8,19.6,19.6v39.2c0,16-12.5,29.3-28.5,30.3v10.7h34.4c2.5-7,4.5-14.1,6.2-21.4,3.8-16,5.7-32.3,5.7-48.7,0-30.1-24.3-54.6-54.5-54.7h-.3c-4.7,0-9.4.6-14,1.8h0c-15.8,4.2-28.9,15.2-35.7,30l-16.8,36.5c-7.2,15.5-19.7,27.8-35.2,34.7-10.7,4.8-20,12.3-26.9,21.8h104.9Z\"><\/path><rect x=\"41.4\" y=\"444.5\" width=\"67.7\" height=\"17.8\"><\/rect><rect x=\"326.6\" y=\"444.5\" width=\"67.7\" height=\"17.8\"><\/rect><path d=\"M203.6,266.2h-12.4c1,14.7,13.7,25.9,28.5,24.9,13.4-.9,24-11.5,24.9-24.9h-12.4c-1,0-1.8-.8-1.8-1.8v-12.5c-2-.1-3.9-.4-5.8-.9-1-.2-1.5-1.2-1.3-2.2s1.2-1.5,2.2-1.3c14.3,3.7,28.9-4.9,32.6-19.2.6-2.2.8-4.4.8-6.7v-39.2c0-8.9-7.2-16-16-16h-9c-.6,12.5-7.2,23.9-17.8,30.6-.8.5-1.8.3-2.4-.5-4-5.6-11.8-6.8-17.4-2.8-5.6,4-6.8,11.8-2.8,17.4,2.3,3.2,6.1,5.1,10.1,5.1,1,0,1.8.8,1.8,1.8v46.3c0,1-.8,1.8-1.8,1.8ZM235.7,216.3h8.9v-16c0-1,.8-1.8,1.8-1.8s1.8.8,1.8,1.8v17.8c0,1-.8,1.8-1.8,1.8h-10.7c-1,0-1.8-.8-1.8-1.8s.8-1.8,1.8-1.8ZM227.4,224c.7-.7,1.8-.7,2.5,0l2,2.1c2.9,2.9,6.8,4.5,10.9,4.5,1,0,1.8.8,1.8,1.8s-.8,1.8-1.8,1.8c-5,0-9.9-2-13.4-5.6l-2-2.1c-.7-.7-.7-1.8,0-2.5h0Z\"><\/path><path d=\"M342.7,266.2h-94.5c-1,16.7-15.3,29.4-32,28.5-15.3-.9-27.6-13.1-28.5-28.5h-94.5c-28.5,0-51.7,23.2-51.7,51.7v123h67.7v-18.9c-17.7-18-23.9-44.2-16.2-68.2l16.3-51.4c.3-.9,1.3-1.5,2.2-1.2.9.3,1.5,1.3,1.2,2.2,0,0,0,0,0,0l-16.3,51.4c-7.3,23-1.2,48.1,15.9,65.2.3.3.5.8.5,1.3v41h210.3v-41c0-.5.2-.9.5-1.3,17.1-17,23.2-42.2,15.9-65.2l-16.3-51.4c-.3-.9.2-1.9,1.1-2.3.9-.3,1.9.2,2.3,1.1,0,0,0,0,0,0l16.3,51.4c7.7,24,1.4,50.3-16.2,68.2v18.9h67.7v-123c0-28.5-23.2-51.7-51.7-51.7Z\"><\/path><path d=\"M260.2,56.2c2.9.4,5.6-1.7,6-4.7.4-2.9-1.7-5.6-4.7-6-.2,0-.4,0-.6,0-3,0-5.3,2.4-5.3,5.3,0,2.7,2,5,4.7,5.3h0Z\"><\/path><path d=\"M238.9,55.6c.5.2.9.6,1,1.2.1.5,0,1.1-.3,1.5-2.5,3.4-1.7,8.1,1.6,10.5,1.2.9,2.7,1.4,4.3,1.5,1.1,0,2.1-.2,3.1-.6.2,0,.4-.1.7-.1.3,0,.6,0,.9.2.5.3.8.7.9,1.3.5,3.3,3.2,5.9,6.6,6.3,3.4.4,6.6-1.5,7.9-4.6.4-.9,1.4-1.3,2.3-1,.1,0,.2.1.4.2,3.4,2.5,8.1,1.7,10.6-1.7,1.5-2.1,1.9-4.9.9-7.3-.2-.5-.2-1.1,0-1.6.3-.5.7-.8,1.3-.9,4.1-.6,7-4.5,6.3-8.6-.4-2.6-2.1-4.8-4.6-5.8-.5-.2-.9-.6-1-1.2-.1-.5,0-1.1.3-1.5,2.5-3.4,1.7-8.1-1.6-10.6-2.1-1.6-4.9-1.9-7.3-.9-.9.4-2,0-2.3-1,0-.1,0-.3-.1-.4-.6-4.1-4.5-7-8.6-6.3-2.6.4-4.8,2.1-5.8,4.6-.4.9-1.4,1.3-2.3,1-.1,0-.2-.1-.4-.2-3.4-2.5-8.1-1.7-10.6,1.6-1.6,2.1-1.9,4.9-.9,7.3.4.9,0,2-1,2.3-.1,0-.3,0-.4.1-4.1.6-7,4.5-6.3,8.6.4,2.6,2.1,4.8,4.6,5.8ZM252,49.8c.6-4.9,5-8.4,9.9-7.8,4.9.6,8.4,5,7.8,9.9-.5,4.5-4.3,7.8-8.8,7.8-.4,0-.7,0-1.1,0-4.9-.6-8.4-5-7.8-9.9h0Z\"><\/path><path d=\"M262.3,102.5l3.9-6.5-7.6.8c-8.8.9-16.2,6.8-19.1,15.2l-.4,1.3h1.3c8.8,1.1,17.3-3.2,21.8-10.7Z\"><\/path><path d=\"M213.3,109.7l1.3-.4c8.3-2.9,14.2-10.3,15.1-19.1l.8-7.6-6.5,3.9c-7.5,4.6-11.8,13.1-10.8,21.8v1.3Z\"><\/path><path d=\"M175.6,87.7l-7.6.7,5.1,5.6c5.9,6.5,15.1,9,23.5,6.4l1.3-.4-.7-1.2c-4.4-7.6-12.9-12-21.6-11.2Z\"><\/path><path d=\"M199.4,79.6l.5-.2c5.8-3.1,9.4-9.3,9-15.9l-.3-5-3.9,3.2c-5.1,4.3-7.2,11.1-5.5,17.4v.5Z\"><\/path><path d=\"M179.8,57.8h.5c0-.1-.3-.6-.3-.6-3.3-5.8-9.6-9.1-16.1-8.6l-5,.4,3.3,3.8c4.4,4.9,11.2,6.9,17.6,5Z\"><\/path><path d=\"M309.8,121.2l3.2-3.8-5-.3c-6.6-.4-12.8,3.1-16,8.9l-.2.5h.5c6.4,1.9,13.2-.2,17.5-5.3Z\"><\/path><path d=\"M298.2,98.1l1.3-.4c8.5-2.3,14.9-9.4,16.4-18l1.3-7.5-6.8,3.5c-7.8,4-12.6,12.3-12.2,21.1v1.3Z\"><\/path><path d=\"M164.4,127.2h1.3c0,0-.3-1.3-.3-1.3-2.3-8.5-9.3-14.9-18-16.4l-7.5-1.3,3.5,6.8c4,7.8,12.2,12.6,21,12.3Z\"><\/path><path d=\"M113.9,68.2l.5-.2c5.8-3.1,9.4-9.3,9-15.9l-.3-5-3.9,3.2c-5.1,4.3-7.2,11.1-5.5,17.4v.5Z\"><\/path><\/g><polygon points=\"75.3 285.9 104.1 254.2 165.7 243.3 174.2 209.2 191.2 174.7 213 159.5 248.2 155.1 260.8 166.4 262.5 182.4 274.1 215.7 268.4 262.7 260.8 287 230.5 310.1 183.6 310.1 165.7 274.5 75.3 285.9\"><\/polygon><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCorsi e laboratori\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1bcaa2 elementor-widget elementor-widget-text-editor\" data-id=\"e1bcaa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Formazione e spazi di condivisione per caregiver e assistenti familiari.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab687ba elementor-widget elementor-widget-bridge_button\" data-id=\"ab687ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bridge_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  itemprop=\"url\" href=\"https:\/\/www.curamieproteggimi.it\/servizi-per-persone-anziane\/corsi-e-laboratori\/\" target=\"_blank\" data-hover-background-color=\"#33BA55\" data-hover-color=\"#FFFFFF\" class=\"qbutton  default\" style=\"color: #FFFFFF; background-color:#22943F;\">Scopri di pi\u00f9<\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-0ad67e6 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-parent\" data-id=\"0ad67e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2e36f06 e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"2e36f06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3d904bd e-con-full e-flex parallax_section_no qode_elementor_container_no e-con e-child\" data-id=\"3d904bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa0d6ad elementor-widget elementor-widget-heading\" data-id=\"aa0d6ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Storie che parlano di noi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf9f43b elementor-widget elementor-widget-text-editor\" data-id=\"cf9f43b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Una rete di persone, enti e luoghi che costruiscono ogni giorno una citt\u00e0 pi\u00f9 lunga, pi\u00f9 giusta e pi\u00f9 umana.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1981d5 elementor-widget elementor-widget-eael-testimonial-slider\" data-id=\"e1981d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;items&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;items_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;items_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;slide_items&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;slide_items_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;slide_items_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\" data-widget_type=\"eael-testimonial-slider.default\">\n\t\t\t\t\t\n        <div class=\"swiper-container-wrap eael-arrow-box eael-testimonial-slider simple-layout\" id=\"eael-testimonial-e1981d5\">\n\t\t\t\t\t\t            <!-- Add Arrows -->\n            <div class=\"swiper-button-next swiper-button-next-e1981d5\">\n                <i class=\"fa fa-arrow-circle-o-right\"><\/i>\n            <\/div>\n            <div class=\"swiper-button-prev swiper-button-prev-e1981d5\">\n                <i class=\"fa fa-arrow-circle-o-left\"><\/i>\n            <\/div>\n\t\t            <div class=\"swiper swiper-8 eael-testimonial-slider-main swiper-container-e1981d5\" data-pagination=\".swiper-pagination-e1981d5\" data-arrow-next=\".swiper-button-next-e1981d5\" data-arrow-prev=\".swiper-button-prev-e1981d5\" data-items=\"1\" data-items-tablet=\"1\" data-items-mobile=\"1\" data-slide-items=\"1\" data-slide-items-tablet=\"1\" data-slide-items-mobile=\"1\" data-margin=\"10\" data-effect=\"slide\" data-speed=\"1500\" data-loop=\"1\" data-arrows=\"1\" data-autoplay_speed=\"7000\">\n\n                <div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-item clearfix swiper-slide  eael-testimonial-align-left\">\n\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-item-inner clearfix\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-content \" style=\"width: 100%; height: px;\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-content\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"eael-testimonial-user\">Claudia e Annarita<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"eael-testimonial-user-company\"><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-text \"><p><span style=\"font-weight: 400\">Una figlia che ha lasciato tutto per assistere la madre. Con il sostegno del progetto, ha trovato equilibrio e serenit\u00e0: \u00abLa mamma ha ripreso a sorridere. Siamo entrambe pi\u00f9 serene\u00bb<\/span><\/p><\/div>\t\t\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-item clearfix swiper-slide  eael-testimonial-align-left\">\n\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-item-inner clearfix\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-content \" style=\"width: 100%; height: px;\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-content\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"eael-testimonial-user\">Liliana, 80 anni, e il teatro della memoria<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"eael-testimonial-user-company\"><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-text \"><p><span style=\"font-weight: 400\">Sola in casa, ha ritrovato voce e appartenenza grazie a un laboratorio teatrale per persone con Alzheimer. \u00abCantava e ballava come se fosse parte del gruppo da sempre\u00bb<\/span><\/p><\/div>\t\t\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-item clearfix swiper-slide  eael-testimonial-align-left\">\n\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-item-inner clearfix\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-content \" style=\"width: 100%; height: px;\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-content\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"eael-testimonial-user\">Maria e Giovanni, una coppia che invecchia insieme<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"eael-testimonial-user-company\"><\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eael-testimonial-text \"><p><span style=\"font-weight: 400\">Due coniugi seguiti fino agli ultimi giorni con supporto psicologico, assistenza e la forza dei figli. \u00abSiete ossigeno sano. Sapere che non siamo soli \u00e8 un grande sollievo\u00bb<\/span><\/p><\/div>\t\t\t\t\t\t\t\t\t\t\t<span class=\"eael-testimonial-quote\"><\/span>\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t                <\/div>\n\t\t\t\t            <\/div>\n\t\t\t        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cosa facciamo Servizi e progetti Il cuore operativo e filantropico della Fondazione La rete sul territorio Dal 2020, con CuraMI &amp; ProteggiMI, la Fondazione ha dato avvio a un modello di prossimit\u00e0 basato su ascolto,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"class_list":["post-11497","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servizi - Fondazione Ravasi Garzanti Onlus<\/title>\n<meta name=\"description\" content=\"Le attivit\u00e0 culturali e creative esercitano un forte potenziale terapeutico nella societ\u00e0, offrendo benessere alle persone di ogni et\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servizi - Fondazione Ravasi Garzanti Onlus\" \/>\n<meta property=\"og:description\" content=\"Le attivit\u00e0 culturali e creative esercitano un forte potenziale terapeutico nella societ\u00e0, offrendo benessere alle persone di ogni et\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Ravasi Garzanti Onlus\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T08:18:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/servizi\\\/\",\"url\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/servizi\\\/\",\"name\":\"Servizi - Fondazione Ravasi Garzanti Onlus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/servizi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/servizi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/persone.svg\",\"datePublished\":\"2026-04-21T10:13:40+00:00\",\"dateModified\":\"2026-05-12T08:18:16+00:00\",\"description\":\"Le attivit\u00e0 culturali e creative esercitano un forte potenziale terapeutico nella societ\u00e0, offrendo benessere alle persone di ogni et\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/servizi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/servizi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/servizi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/persone.svg\",\"contentUrl\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/persone.svg\",\"width\":708,\"height\":708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/servizi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/#website\",\"url\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/\",\"name\":\"Fondazione Ravasi Garzanti Onlus\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mg-adv.com\\\/fondazione-ravasi-garzanti\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servizi - Fondazione Ravasi Garzanti Onlus","description":"Le attivit\u00e0 culturali e creative esercitano un forte potenziale terapeutico nella societ\u00e0, offrendo benessere alle persone di ogni et\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/","og_locale":"it_IT","og_type":"article","og_title":"Servizi - Fondazione Ravasi Garzanti Onlus","og_description":"Le attivit\u00e0 culturali e creative esercitano un forte potenziale terapeutico nella societ\u00e0, offrendo benessere alle persone di ogni et\u00e0.","og_url":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/","og_site_name":"Fondazione Ravasi Garzanti Onlus","article_modified_time":"2026-05-12T08:18:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/","url":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/","name":"Servizi - Fondazione Ravasi Garzanti Onlus","isPartOf":{"@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/#primaryimage"},"image":{"@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/#primaryimage"},"thumbnailUrl":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-content\/uploads\/2026\/04\/persone.svg","datePublished":"2026-04-21T10:13:40+00:00","dateModified":"2026-05-12T08:18:16+00:00","description":"Le attivit\u00e0 culturali e creative esercitano un forte potenziale terapeutico nella societ\u00e0, offrendo benessere alle persone di ogni et\u00e0.","breadcrumb":{"@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/#primaryimage","url":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-content\/uploads\/2026\/04\/persone.svg","contentUrl":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-content\/uploads\/2026\/04\/persone.svg","width":708,"height":708},{"@type":"BreadcrumbList","@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/servizi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/"},{"@type":"ListItem","position":2,"name":"Servizi"}]},{"@type":"WebSite","@id":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/#website","url":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/","name":"Fondazione Ravasi Garzanti Onlus","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"campaignId":"","_links":{"self":[{"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/pages\/11497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/comments?post=11497"}],"version-history":[{"count":88,"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/pages\/11497\/revisions"}],"predecessor-version":[{"id":12172,"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/pages\/11497\/revisions\/12172"}],"wp:attachment":[{"href":"https:\/\/mg-adv.com\/fondazione-ravasi-garzanti\/wp-json\/wp\/v2\/media?parent=11497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}